{"id":7808,"date":"2025-02-25T13:15:29","date_gmt":"2025-02-25T16:15:29","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/una-pareja-es-obligada-a-sentarse-junto-al-cadaver-de-una-mujer-durante-un-vuelo-de-15-horas\/"},"modified":"2025-02-25T13:15:29","modified_gmt":"2025-02-25T16:15:29","slug":"una-pareja-es-obligada-a-sentarse-junto-al-cadaver-de-una-mujer-durante-un-vuelo-de-15-horas","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/una-pareja-es-obligada-a-sentarse-junto-al-cadaver-de-una-mujer-durante-un-vuelo-de-15-horas\/","title":{"rendered":"Una pareja es obligada a sentarse junto al cada\u0301ver de una mujer durante un vuelo\u00a0de\u00a015\u00a0horas"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"cuerpo\">\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Era el viaje so\u00f1ado. Hac\u00eda a\u00f1os que ten\u00edan la fantas\u00eda de hacerlo pero por una u otra cosa siempre se pospuso. El destino era la maravillosa Venecia, tan c\u00e9lebre como m\u00edtica. Y finalmente, luego de una larga organizaci\u00f3n, el d\u00eda lleg\u00f3, y l<strong>a pareja feliz se sub\u00eda al avi\u00f3n <\/strong>que comenzar\u00eda la aventura.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Pero entonces, lo imprevisto. Y as\u00ed, la pareja feliz ya no lo fue. Y el viaje de ensue\u00f1o se transform\u00f3<strong> en la peor experiencia de su vida<\/strong>. Porque luego de algunas horas de un vuelo tranquilo, una emergencia m\u00e9dica de una mujer convirti\u00f3 al viaje en una pesadilla.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Sucedi\u00f3 que la mujer, que no fue identificada, muri\u00f3 all\u00ed mismo y seg\u00fan denunci\u00f3 la pareja, <strong>sentaron al cad\u00e1ver de la mujer<\/strong> junto a ellos por el resto del viaje, lo que signific\u00f3 6 horas.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Mitchell Ring y Jennifer Colin viajaban por Qatar Airways desde Melbourne, Australia, a Doha, Qatar, en un primer tramo de su viaje rumbo a la bella Italia, cuando la pasajera sufri\u00f3 un ataque al coraz\u00f3n, seg\u00fan especularon, que oblig\u00f3 a la tripulaci\u00f3n a <strong>recostarla en el pasillo para atenderla.<\/strong><\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>\u201cDesafortunadamente, la se\u00f1ora no pudo ser salvada, fue <strong>bastante desgarrador de ver<\/strong>\u201d, cont\u00f3 luego Ring al programa de televisi\u00f3n \u201cA Current Affair\u201d.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>\u201cIntentaron llevarla en silla de ruedas hasta la clase ejecutiva, pero era una mujer bastante grande y <strong>no pudieron pasarla por el pasillo<\/strong>\u201d, describi\u00f3 el hombre.<\/p>\n<\/div>\n<div class=\"sc-198be8ec-0 cynXbu image-embed  image-embed \"><picture class=\"sc-198be8ec-1 kOjRiQ\"><source media=\"(min-width: 975px)\" width=\"720\" height=\"480\" \/><img alt=\"La pareja asegur\u00f3 que el incidente les arruin\u00f3 el viaje que hab\u00edan esperado tanto tiempo.\" loading=\"lazy\" width=\"720\" height=\"480\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/02\/Una-pareja-es-obligada-a-sentarse-junto-al-cadaver-de.jpg\"\/><span class=\"epigraphe\">La pareja asegur\u00f3 que el incidente les arruin\u00f3 el viaje que hab\u00edan esperado tanto tiempo.<\/span><span class=\"bkg\"\/><span class=\"picture-open\"><button class=\"open-image\" aria-label=\"Open Image\"\/><\/span><\/picture><\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>La pareja australiana, que ten\u00eda dos asientos libres en su fila de cuatro, dijo que la tripulaci\u00f3n de vuelo \u201cfrustrada por no saber qu\u00e9 hacer\u201d les pidi\u00f3 que se movieran para poder apoyar el cad\u00e1ver junto a ellos.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>\u201cDijeron: \u2018\u00bfPuedes moverte, por favor?\u2019 y yo solo dije: \u2018S\u00ed, no hay problema\u2019\u201d, cont\u00f3. \u201cLuego<strong> colocaron a la se\u00f1ora en el asiento en la que yo estaba<\/strong>\u201d.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Una fotograf\u00eda impactante de la terrible experiencia captur\u00f3 a Ring mirando su televisor mientras <strong>el cuerpo de la mujer estaba sentado a su lad<\/strong>o. El hombre afirma que pas\u00f3 seis horas sentado junto al cuerpo de la mujer, que fue cubierto por una manta.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Cuando finalmente aterrizaron, la pareja denunci\u00f3 que la tripulaci\u00f3n de la aerol\u00ednea les pidi\u00f3 que <strong>permanecieran en sus asientos mientras los socorristas<\/strong> llegaban a recuperar el cuerpo.<\/p>\n<\/div>\n<div class=\"sc-198be8ec-0 cynXbu image-embed  image-embed \"><picture class=\"sc-198be8ec-1 kOjRiQ\"><source media=\"(min-width: 975px)\" width=\"720\" height=\"480\" \/><img alt=\"El hombre estuvo sentado junto al cad\u00e1ver durante seis horas.\" loading=\"lazy\" width=\"720\" height=\"480\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/02\/1740500129_891_Una-pareja-es-obligada-a-sentarse-junto-al-cadaver-de.jpg\"\/><span class=\"epigraphe\">El hombre estuvo sentado junto al cad\u00e1ver durante seis horas.<\/span><span class=\"bkg\"\/><span class=\"picture-open\"><button class=\"open-image\" aria-label=\"Open Image\"\/><\/span><\/picture><\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>\u201cNo puedo creer que nos dijeran que nos qued\u00e1ramos\u2026 eso definitivamente no estuvo nada bien. Lo \u00fanico que quer\u00edamos er<strong>a salir de all\u00ed cuanto antes<\/strong>\u201d, dijo Ring.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Qatar Airways inform\u00f3, luego de que la noticia cobr\u00f3 trascendencia, que estaban en <strong>proceso de comunicarse<\/strong> con la pareja a ra\u00edz de la terrible experiencia.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>\u201cEn primer lugar, nuestros pensamientos est\u00e1n con la familia del pasajero que lamentablemente <strong>falleci\u00f3 a bordo de nuestro vuelo<\/strong>\u201d, sostuvo un portavoz de Qatar Airways en un comunicado que publicaron en sus redes sociales.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>\u201cPedimos disculpas por cualquier inconveniente o angustia que este incidente pueda haber causado y estamos en proceso de comunicarnos con los pasajeros de acuerdo <strong>con nuestras pol\u00edticas y procedimientos<\/strong>\u201d, cerr\u00f3 la aerol\u00ednea.<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/internacional\/pareja-obligada-sentarse-junto-cadaver-mujer-vuelo-de-15-horas_0_2XJAfLXbOj.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era el viaje so\u00f1ado. Hac\u00eda a\u00f1os que ten\u00edan la fantas\u00eda de hacerlo pero por una u otra cosa siempre se pospuso. El destino era la maravillosa Venecia, tan c\u00e9lebre como m\u00edtica. Y finalmente, luego de una larga organizaci\u00f3n, el d\u00eda lleg\u00f3, y la pareja feliz se sub\u00eda al avi\u00f3n que comenzar\u00eda la aventura. Pero entonces, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[9176,1549,776,138,9174,1667,9175,73,9177],"class_list":["post-7808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-cadaver","tag-durante","tag-junto","tag-mujer","tag-obligada","tag-pareja","tag-sentarse","tag-una","tag-vuelode15horas"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7808"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/7809"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}