{"id":46916,"date":"2025-07-31T18:39:59","date_gmt":"2025-07-31T21:39:59","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/saca-a-cavani-perdona-a-merentiel-y-le-da-el-poder-a-paredes\/"},"modified":"2025-07-31T18:39:59","modified_gmt":"2025-07-31T21:39:59","slug":"saca-a-cavani-perdona-a-merentiel-y-le-da-el-poder-a-paredes","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/saca-a-cavani-perdona-a-merentiel-y-le-da-el-poder-a-paredes\/","title":{"rendered":"saca a Cavani, perdona a Merentiel y le da el poder a Paredes"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/las-dos-increibles-chances-erradas-y-el-fin-de-una.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p><strong>Miguel \u00c1ngel Russo<\/strong> es un sabio del f\u00fatbol y entiende los momentos casi como ning\u00fan otro protagonista. Sabe el entrenador de 69 a\u00f1os que <strong>Boca <\/strong>atraviesa una severa crisis, por supuesto. Por eso en las \u00faltimas conferencias de prensa, luego de las duras ca\u00eddas ante <strong>Atl\u00e9tico Tucum\u00e1n<\/strong> y <strong>Hurac\u00e1n<\/strong>, se cuid\u00f3 bastante m\u00e1s que de costumbre. Pero dej\u00f3 un par de frases que se pod\u00edan leer entrel\u00edneas y que con el correr de la semana se hicieron potentes. <\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>\u201cYo me hago cargo de todo porque corresponde que lo haga. Habr\u00e1 que encontrarle la vuelta, mejorar y seguir trabajando\u201d, solt\u00f3 el t\u00e9cnico en el pesado vestuario del <strong>Tom\u00e1s Adolfo Duc\u00f3<\/strong>. Y lanz\u00f3: \u201cLleg\u00f3 el momento de cambiar algunas cosas\u201d. \u00bfY qu\u00e9 sucedi\u00f3 en las pr\u00e1cticas de f\u00fatbol en el predio de Ezeiza? Russo tom\u00f3 dos determinaciones que hacen ruido: opt\u00f3 por no castigar a <strong>Miguel Merentiel <\/strong>y sac\u00f3 del equipo titular a <strong>Edinson Cavani<\/strong>, el uruguayo que ya es cuestionado por los hinchas de Boca.<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>El titular es poderoso: <strong>Russo puso a Cavani para los suplentes<\/strong>. Si bien fue una prueba, la sensaci\u00f3n es que el <em>Matador <\/em>no ser\u00e1 titular en el crucial juego del s\u00e1bado 9 contra Racing en la Bombonera. Igual, la no presencia del goleador no causar\u00eda demasiado malestar entre los simpatizantes del club porque <strong>hace meses que es pobre el nivel del uruguayo<\/strong>. Encima, en lo que va del a\u00f1o se perdi\u00f3 varios encuentros por distintas lesiones.<strong> El delantero jug\u00f3 16 de los 28 partidos de Boca en el semestre y anot\u00f3 3 goles.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p>Existen dos cuestiones que hacen algo de alboroto con Cavani. La primera es futbol\u00edstica: e<strong>l aporte de Merentiel, el mejor por varios cuerpos de ventaja en el Mundial de Clubes, baja demasiado cuando debe compartir cancha con su compatriota<\/strong>. Ocurre que la <em>Bestia <\/em>debe cambiar su manera de jugar con su compatriota a su lado<strong>. Un dato sirve para graficar: 7 de los 8 goles que anot\u00f3 Merentiel en lo que va del 2025 los hizo sin Cavani en la cancha<\/strong>. El \u00fanico festejo que los encontr\u00f3 juntos fue en el 2-0 ante Estudiantes por el Apertura.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p><strong>El segundo asunto que gira en torno a Cavani en los \u00faltimos d\u00edas es una presunta falta de generosidad al no entregarle la cinta de capit\u00e1n a Leandro Paredes<\/strong>, quien ser\u00e1 el l\u00edder del equipo en las pr\u00f3ximas temporadas. No fueron pocos los hinchas que esperaron el gesto del uruguayo para con el campe\u00f3n del mundo. Y se escribe en potencial porque tal vez puertas para adentro existi\u00f3 una charla entre ambos futbolistas. Pero cuesta creer que eso no haya trascendido.<\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>As\u00ed, <strong>Russo mata a dos p\u00e1jaros de un tiro con la suplencia de Cavani: le da m\u00e1s libertades a Merentiel y todo el poder a Paredes.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-7\">\n<p>Claro que lo de Cavani no ser\u00e1 el \u00fanico movimiento que planea el entrenador: tambi\u00e9n habr\u00eda modificaci\u00f3n en el sistema de juego. Russo comenz\u00f3 su ciclo con un 4-2-3-1 ante Benfica en el Mundial de Clubes y lo que asoma para medirse contra la Academia es un 4-4-2. Tiene sentido: el DT apelar\u00e1 al sistema que necesita menos trabajo para afrontar un encuentro que ser\u00e1 clave para su futuro.<strong> Un rumor que tambi\u00e9n circul\u00f3 en las \u00faltimas horas se\u00f1ala que el entrenador podr\u00eda dejar el cargo en caso de una ca\u00edda dolorosa ante los comandados por Gustavo Costas.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>\u00bfOtras novedades que se desprenden del ensayo formal de f\u00fatbol? <strong>Kevin Zen\u00f3n <\/strong>reapareci\u00f3 como volante por izquierda y por la derecha lo hizo <strong>Brian Aguirre<\/strong>, quien apenas suma 227 minutos en lo que va del a\u00f1o. La idea es que ambos hagan un gran recorrido para asistir a los delanteros Merentiel y<strong> Milton Gim\u00e9nez<\/strong>, en definitiva el que se meti\u00f3 por Cavani.<\/p>\n<\/div>\n<div id=\"element-body-10\">\n<p>En el mediocampo habr\u00e1 una nueva oportunidad para el juvenil Milton Delgado, aunque est\u00e1 vez no ser\u00e1 interior izquierdo sino que se repartir\u00e1 el centro con Paredes.<\/p>\n<\/div>\n<div id=\"element-body-11\">\n<p>En la defensa, el lateral derecho sigue en oferta y Russo apostar\u00eda ahora por Juan Barinaga, titular ante los tucumanos por Copa Argentina. Luis Adv\u00edncula jug\u00f3 para los suplentes, lo mismo que Frank Fabra, Alan Velasco, Williams Alarc\u00f3n, Tom\u00e1s Belmonte, Malcom Braida y Exequiel Zeballos.<\/p>\n<\/div>\n<div id=\"element-body-12\">\n<p>En el arco, Agust\u00edn Marches\u00edn estuvo ausente porque viene arrastrando una sobrecarga muscular: ataj\u00f3 Leandro Brey.<\/p>\n<\/div>\n<div id=\"element-body-14\">\n<p>Ojo: Nicol\u00e1s Figal y Ayrton Costas podr\u00edan meterse en el equipo en caso de recibir el alta m\u00e9dica.<\/p>\n<\/div>\n<div id=\"element-body-15\">\n<p>Pas\u00f3 la pr\u00e1ctica de f\u00fatbol y Russo cumpli\u00f3 con lo que avis\u00f3: hizo cambios. Y Cavani fue el que pag\u00f3.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/deportes\/bandas-russo-vuelve-jugar-fuerte-capear-temporal-boca-saca-cavani-perdona-merentiel-da-poder-paredes_0_W5PLZFLy39.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miguel \u00c1ngel Russo es un sabio del f\u00fatbol y entiende los momentos casi como ning\u00fan otro protagonista. Sabe el entrenador de 69 a\u00f1os que Boca atraviesa una severa crisis, por supuesto. Por eso en las \u00faltimas conferencias de prensa, luego de las duras ca\u00eddas ante Atl\u00e9tico Tucum\u00e1n y Hurac\u00e1n, se cuid\u00f3 bastante m\u00e1s que de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2699,5210,859,25027,2140,13413],"class_list":["post-46916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-cavani","tag-merentiel","tag-paredes","tag-perdona","tag-poder","tag-saca"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46916"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/44939"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}