{"id":46891,"date":"2025-07-31T16:48:57","date_gmt":"2025-07-31T19:48:57","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/que-le-espera-a-alvaro-uribe-tras-su-condena-por-corrupcion\/"},"modified":"2025-07-31T16:48:57","modified_gmt":"2025-07-31T19:48:57","slug":"que-le-espera-a-alvaro-uribe-tras-su-condena-por-corrupcion","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/que-le-espera-a-alvaro-uribe-tras-su-condena-por-corrupcion\/","title":{"rendered":"\u00bfQu\u00e9 le espera a \u00c1lvaro Uribe tras su condena por corrupci\u00f3n?"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/\u00bfQue-le-espera-a-Alvaro-Uribe-tras-su-condena-por.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>Condenado por delitos de soborno y fraude procesal, el ex presidente colombiano <strong>\u00c1lvaro Uribe<\/strong> conocer\u00e1 el viernes por parte de una jueza la pena que le espera. \u00bfIr\u00e1 a prisi\u00f3n?, \u00bfpodr\u00e1 defenderse en libertad?, \u00bfhay lugar a la prescripci\u00f3n del caso? Estos son los escenarios posibles.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>El lunes un tribunal hall\u00f3 culpable al ex mandatario (2002-2010) de obstruir a la justicia y manipular a paramilitares para evitar que lo vincularan con esos escuadrones de ultraderecha que en medio del conflicto armado con las guerrillas de izquierda cometieron numerosas masacres contra civiles.<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>El fallo en primera instancia, anunciado en una audiencia que se extendi\u00f3 por 11 horas, lo expone a pasar<strong> hasta 12 a\u00f1os en prisi\u00f3n<\/strong>. Pero la defensa del popular pol\u00edtico de derecha, de 73 a\u00f1os, anunci\u00f3 que <strong>apelar\u00e1,<\/strong> lo que abre un nuevo cap\u00edtulo de esta saga judicial.<\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p>El proceso se remonta a 2012, cuando Uribe demand\u00f3 ante la corte suprema al senador de izquierda Iv\u00e1n Cepeda por asegurar p\u00fablicamente que paramilitares encarcelados dec\u00edan tener nexos con el ex mandatario.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p><strong>El caso dio un giro en 2018 y el ex presidente pas\u00f3 de demandante a investigado,<\/strong> al ser se\u00f1alado de manipular a testigos para perjudicar a Cepeda.<\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>En medio de las investigaciones en 2020 Uribe, que entonces era senador, renunci\u00f3 al Congreso en una maniobra que le hizo perder sus fueros e hizo que el caso pasara a la justicia ordinaria.<\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>Estos son los caminos que se abren ahora: el viernes &#8220;conoceremos cu\u00e1l es el monto de la sanci\u00f3n&#8221;, es decir cu\u00e1ntos a\u00f1os deber\u00eda pasar Uribe en prisi\u00f3n, y si la jueza ordenar\u00e1 que sea capturado de &#8220;inmediato&#8221; o si &#8220;le va a permitir, como lo dice la ley, defenderse en libertad&#8221;, explica a la AFP el abogado penalista Francisco Bernate.<\/p>\n<\/div>\n<div id=\"element-body-9\">\n<p>Para los delitos por los que fue condenado, denominados &#8220;soborno en acci\u00f3n penal&#8221; y &#8220;fraude procesal&#8221;, el c\u00f3digo penal dispone penas de<strong> m\u00e1ximo ocho y 12 a\u00f1os respectivamente<\/strong>, precis\u00f3 Dalila Henao, miembro de la junta directiva del Colegio de Abogados Penalistas de Colombia.<\/p>\n<\/div>\n<div id=\"element-body-10\">\n<p>Los juristas coinciden en que el escenario m\u00e1s probable es que Uribe se defienda en libertad mientras se resuelve su apelaci\u00f3n, recurso que la defensa deber\u00e1 anunciar luego de que el viernes la jueza exponga el detalle de las m\u00e1s de 1.000 p\u00e1ginas del veredicto.<\/p>\n<\/div>\n<div id=\"element-body-12\">\n<p><strong>La fiscal\u00eda pidi\u00f3 nueve a\u00f1os de prisi\u00f3n domiciliaria<\/strong>. La defensa anunci\u00f3 que el 11 de agosto presentar\u00e1 una apelaci\u00f3n del fallo ante el Tribunal Superior de Bogot\u00e1.<\/p>\n<\/div>\n<div id=\"element-body-13\">\n<p>Seg\u00fan el equipo jur\u00eddico del ex gobernante, &#8220;esta no es una decisi\u00f3n definitiva: la presunci\u00f3n de inocencia del expresidente Uribe permanece intacta y a\u00fan existen recursos pendientes&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-14\">\n<p>Ante la apelaci\u00f3n, el Tribunal Superior tendr\u00e1 dos caminos: &#8220;Confirmar la decisi\u00f3n de la jueza&#8221;, es decir la condena, o &#8220;revocar el fallo de primera instancia y absolverlo&#8221;, dice Henao.<\/p>\n<\/div>\n<div id=\"element-body-15\">\n<p>Uribe insiste en que la grabaci\u00f3n con una c\u00e1mara instalada en un &#8220;reloj esp\u00eda&#8221; para registrar el soborno de uno de sus abogados fue manipulada y no puede usarse como prueba.<\/p>\n<\/div>\n<div id=\"element-body-16\">\n<p>En ella el jurista Diego Cadena, que enfrenta su propio juicio, intenta sobornar al testigo estrella Juan Guillermo Monsalve, quien acusa al ex presidente de haber conformado un grupo paramilitar junto a su hermano Santiago.<\/p>\n<\/div>\n<div id=\"element-body-17\">\n<p>La defensa del ex mandatario tambi\u00e9n sostiene que las escuchas a su tel\u00e9fono son una violaci\u00f3n a la privacidad.<\/p>\n<\/div>\n<div id=\"element-body-18\">\n<p>Miguel \u00c1ngel del R\u00edo, uno de los abogados de la contraparte, explic\u00f3 a la AFP que el Tribunal Superior de Bogot\u00e1 debe tomar una decisi\u00f3n antes del 16 de octubre o &#8220;de lo contrario prescribir\u00e1 la acci\u00f3n penal&#8221; y el caso se archivar\u00e1.<\/p>\n<\/div>\n<div id=\"element-body-19\">\n<p>El deseo de los demandantes es que &#8220;cada uno de esos hechos jur\u00eddicamente relevantes se confirmen y se materialicen&#8221; tras un proceso de m\u00e1s de una d\u00e9cada.<\/p>\n<\/div>\n<div id=\"element-body-20\">\n<p>Pese a la carrera contra el reloj, Henao ve poco probable que el proceso prescriba &#8220;por ser un caso tan relevante&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-21\">\n<p>Bernate coincide: &#8220;El tribunal nunca deja prescribir un caso&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-22\">\n<p>Sin importar cu\u00e1l sea la decisi\u00f3n del Tribunal Superior de Bogot\u00e1, si cualquiera de las partes apela, el caso podr\u00eda volver a donde todo empez\u00f3: la Corte Suprema de Justicia.<\/p>\n<\/div>\n<div id=\"element-body-23\">\n<p>En caso de estar en desacuerdo con la decisi\u00f3n del tribunal, la defensa, la fiscal\u00eda o el ministerio p\u00fablico pueden presentar un recurso de casaci\u00f3n ante la corte, que tiene hasta cinco a\u00f1os para dar un dictamen, explica Henao.<\/p>\n<\/div>\n<div id=\"element-body-24\">\n<p>Una vez lo haga, no habr\u00e1 espacio a ninguna acci\u00f3n adicional.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/mundo\/expectativa-colombia-espera-alvaro-uribe-condena-corrupcion_0_cQDKkm015b.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Condenado por delitos de soborno y fraude procesal, el ex presidente colombiano \u00c1lvaro Uribe conocer\u00e1 el viernes por parte de una jueza la pena que le espera. \u00bfIr\u00e1 a prisi\u00f3n?, \u00bfpodr\u00e1 defenderse en libertad?, \u00bfhay lugar a la prescripci\u00f3n del caso? Estos son los escenarios posibles. El lunes un tribunal hall\u00f3 culpable al ex mandatario [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[15750,4668,4433,463,142,286,312,20564],"class_list":["post-46891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-alvaro","tag-condena","tag-corrupcion","tag-espera","tag-por","tag-que","tag-tras","tag-uribe"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46891"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46892"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}