{"id":46881,"date":"2025-07-31T15:58:00","date_gmt":"2025-07-31T18:58:00","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/aseguran-que-rufina-cabre-se-quedaria-a-vivir-en-turquia-con-la-china-suarez-y-mauro-icardi\/"},"modified":"2025-07-31T15:58:00","modified_gmt":"2025-07-31T18:58:00","slug":"aseguran-que-rufina-cabre-se-quedaria-a-vivir-en-turquia-con-la-china-suarez-y-mauro-icardi","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/aseguran-que-rufina-cabre-se-quedaria-a-vivir-en-turquia-con-la-china-suarez-y-mauro-icardi\/","title":{"rendered":"Aseguran que Rufina Cabr\u00e9 se quedar\u00eda a vivir en Turqu\u00eda con La China Su\u00e1rez y Mauro Icardi"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/Aseguran-que-Rufina-Cabre-se-quedaria-a-vivir-en-Turquia.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>Este jueves sorprendi\u00f3 la noticia que asegura que<strong> Rufina Cabr\u00e9<\/strong>, la hija que tienen en com\u00fan <strong>Eugenia \u201cLa China\u201d Su\u00e1rez <\/strong>y <strong>Nicol\u00e1s Cabr\u00e9<\/strong>, no volver\u00eda a la Argentina y se quedar\u00eda a vivir en Turqu\u00eda junto a su mam\u00e1 y <strong>Mauro Icardi.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>Hace algunos d\u00edas trascendieron rumores que indicaban que, antes de partir de vacaciones hacia Estambul, la ni\u00f1a de 12 a\u00f1os hab\u00eda celebrado su cumplea\u00f1os con amigas y que se hab\u00eda despedido de ellas diciendo que se ir\u00eda a vivir a Estambul, donde est\u00e1 instalado el nuevo novio de la ex <em>Casi \u00c1ngeles.<\/em><\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>Por estas horas en<em> Intrusos <\/em>(Am\u00e9rica) contaron que el jugador del Galatasaray y su pareja <strong>estar\u00edan a punto de mudarse a una mansi\u00f3n m\u00e1s grande como parte del proyecto familiar que tienen en com\u00fan.<\/strong> La casa ser\u00eda muy lujosa y tendr\u00eda vistas hermosas.<\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p><strong>\u201cEl 8 de agosto Rufina Cabr\u00e9 empieza el colegio en Turqu\u00eda. El colegio es de doble escolaridad, biling\u00fce, turco e ingl\u00e9s, totalmente asentada en Turqu\u00eda con su madre y con la pareja de su madre\u201d<\/strong>, manifest\u00f3 Karina Iav\u00edcoli, panelista del programa de espect\u00e1culos.<\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>En l\u00ednea con eso, la periodista cont\u00f3 que, por otro lado, Magnolia y Amancio, los hijos que La China tiene con <strong>Benjam\u00edn Vicu\u00f1a<\/strong> y que actualmente tambi\u00e9n se encuentran de vacaciones con ella en Estambul, volver\u00edan al pa\u00eds en breve para reencontrarse con su pap\u00e1 y continuar con su rutina habitual.<\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>Sobre Cabr\u00e9, explic\u00f3: &#8220;Nicol\u00e1s Cabr\u00e9 y La China siempre se manejaron de una manera natural. \u00c9l no tendr\u00eda problema de viajar a Turqu\u00eda. \u00c9l est\u00e1 con su novia, se est\u00e1 por casar a fin de a\u00f1o. Lo que me dicen es que, aunque ellos dicen que no, que en los planes de ellos estar\u00eda tambi\u00e9n, en alg\u00fan momento no muy lejano, tener un beb\u00e9&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-7\">\n<p>Adem\u00e1s, aseguran que Eugenia no tendr\u00eda planes de volver al pa\u00eds y que su idea ser\u00eda que Magnolia y Amancio tambi\u00e9n se queden en Turqu\u00eda m\u00e1s adelante.<\/p>\n<\/div>\n<div id=\"element-body-9\">\n<p>Este jueves Nicol\u00e1s Cabr\u00e9 estuvo en Perros de la calle, el ciclo radial que conduce Andy Kusnetzoff y habl\u00f3 sobre Rufina, la hija que tiene con La China Su\u00e1rez.<\/p>\n<\/div>\n<div id=\"element-body-10\">\n<p>Consultado sobre c\u00f3mo maneja la sobreexposici\u00f3n de la ex <em>Casi \u00c1ngeles<\/em>, el artista explic\u00f3: \u201c<strong>Rufina sabe perfectamente quienes somos y su vida no tiene nada que ver con lo que se dice que es. <\/strong>Nosotros somos normales. Trato de ocuparme de que ella entienda que lo importante en la vida es otra cosa\u201d.<\/p>\n<\/div>\n<div id=\"element-body-12\">\n<p>\u201cYo me quedo tranquilo sabiendo que ella tiene claras las cosas como son. <strong>Nunca jam\u00e1s en la vida de un hijo ten\u00e9s que ser un obst\u00e1culo. Creo que al ser padre muchas veces uno tiene que poner el pecho y si hay alguien que le tiene que doler algo, sos vos<\/strong>\u201d, se sincer\u00f3.<\/p>\n<\/div>\n<div id=\"element-body-13\">\n<p>El actor tambi\u00e9n se refiri\u00f3 a su casamiento con Roc\u00edo Pardo, destac\u00f3 que va a ser algo \u201cmuy relajado y muy tranquilo\u201d.<\/p>\n<\/div>\n<div id=\"element-body-14\">\n<p>\u201cNosotros nos parecemos mucho y creo que esa es la caracter\u00edstica m\u00e1s grande nuestra. Somos muy compatibles. Hoy por hoy soy el hombre m\u00e1s feliz del mundo. Conoc\u00ed una persona que me hace absolutamente feliz\u201d, se sincer\u00f3 sobre su relaci\u00f3n con la directora.<\/p>\n<\/div>\n<div id=\"element-body-15\">\n<p>Adem\u00e1s, se\u00f1al\u00f3 que es \u201cun amor sano\u201d: \u201cHace un a\u00f1o y medio que me voy a dormir todos los d\u00edas sonriendo. Me despierto todos los d\u00edas sonriendo con mi mujer, con mi amiga, mi compa\u00f1era\u201d.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/fama\/aseguran-rufina-cabre-quedaria-vivir-turquia-china-suarez-mauro-icardi_0_vxywDCwhX3.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves sorprendi\u00f3 la noticia que asegura que Rufina Cabr\u00e9, la hija que tienen en com\u00fan Eugenia \u201cLa China\u201d Su\u00e1rez y Nicol\u00e1s Cabr\u00e9, no volver\u00eda a la Argentina y se quedar\u00eda a vivir en Turqu\u00eda junto a su mam\u00e1 y Mauro Icardi. Hace algunos d\u00edas trascendieron rumores que indicaban que, antes de partir de vacaciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3687,1693,72,18,133,132,5560,10330,131,2836,1513],"class_list":["post-46881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-aseguran","tag-cabre","tag-china","tag-con","tag-icardi","tag-mauro","tag-quedaria","tag-rufina","tag-suarez","tag-turquia","tag-vivir"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46881"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46882"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}