{"id":46797,"date":"2025-07-31T11:40:03","date_gmt":"2025-07-31T14:40:03","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/cuatro-suicidios-entre-ellos-un-soldado\/"},"modified":"2025-07-31T11:40:03","modified_gmt":"2025-07-31T14:40:03","slug":"cuatro-suicidios-entre-ellos-un-soldado","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/cuatro-suicidios-entre-ellos-un-soldado\/","title":{"rendered":"cuatro suicidios, entre ellos un soldado"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/cuatro-suicidios-entre-ellos-un-soldado.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>Un soldado voluntario del Ej\u00e9rcito fue encontrado muerto en un predio militar abandonado, en <strong>Curuz\u00fa Cuati\u00e1<\/strong>, Corrientes. \u201c<em>Me denunciaste, voy a tener problemas en el Ej\u00e9rcito<\/em>\u201d, fue el \u00faltimo mensaje que le envi\u00f3 a su ex novia, quien hab\u00eda decidido cortar el v\u00ednculo unas horas antes y realiz\u00f3 una exposici\u00f3n ante la Comisar\u00eda de la Mujer.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>La investigaci\u00f3n se dispar\u00f3 el lunes a las 16.30 cuando una pareja que lleg\u00f3 al predio del ex Batall\u00f3n de Log\u00edstica 3 y descubri\u00f3 el cuerpo de <strong>Armando Rafael Mi\u00f1o (21)<\/strong> pendiendo de un trozo de pl\u00e1stico que hab\u00eda anudado a una viga de un tanque de agua en desuso.<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>La Polic\u00eda no tard\u00f3 en llegar al lugar -est\u00e1 a unos cinco kil\u00f3metros de Curuz\u00fa Cuati\u00e1, sobre el viejo trazado de la ruta nacional 14- junto al fiscal Oscar Ca\u00f1ete y el m\u00e9dico policial Alejandro Lima, quien constat\u00f3 que la muerte hab\u00eda sido reciente.<\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>El cuerpo estaba a unos diez metros de altura, en el pulm\u00f3n del tanque, y no se hallaron indicios de que el robusto soldado voluntario haya sido v\u00edctima de un homicidio. <\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>\u201cPara quitarse la vida utiliz\u00f3 un nylon muy grueso que asegur\u00f3 a una viga con un trozo de alambre, a unos diez metros de altura\u201d, sostuvo un funcionario que estuvo en el lugar.<\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>En uno de los bolsillos del soldado -al momento del hecho no vest\u00eda el uniforme- se hall\u00f3 su tel\u00e9fono celular. Los polic\u00edas activaron el aparato y constataron que se trataba de un militar por la foto que ten\u00eda como fondo de pantalla.<\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>Mi\u00f1o era de <strong>Alen Cu\u00e9<\/strong>, un inh\u00f3spito paraje del departamento La Cruz, y desde hace un tiempo prestaba servicios en el cuartel de Curuz\u00fa Cuati\u00e1. <\/p>\n<\/div>\n<div id=\"element-body-9\">\n<p>El joven estaba bajo tratamiento psicol\u00f3gico en la unidad militar y estaba de novio con una joven de esa ciudad.<\/p>\n<\/div>\n<div id=\"element-body-10\">\n<p>Esta persona ser\u00eda clave para reconstruir las \u00faltimas horas de vida de Mi\u00f1o. Ella hab\u00eda puesto punto final a la relaci\u00f3n ese mismo d\u00eda y se hab\u00eda presentado en la Comisar\u00eda de la Mujer para realizar una exposici\u00f3n, con la aparente intenci\u00f3n de que Mi\u00f1o no insistiera en retomar el v\u00ednculo.<\/p>\n<\/div>\n<div id=\"element-body-12\">\n<p>Una oficial de la comisar\u00eda intent\u00f3 comunicarse telef\u00f3nicamente con el soldado, pero no pudo. Es por eso que le envi\u00f3 un mensaje, notific\u00e1ndole de la presentaci\u00f3n de la joven.<\/p>\n<\/div>\n<div id=\"element-body-13\">\n<p>Cerca de las 15, Mi\u00f1o le envi\u00f3 un \u00faltimo mensaje a su ex: \u201c<em>Me denunciaste, voy a tener problemas en el Ej\u00e9rcito<\/em>\u201d, le dijo.<\/p>\n<\/div>\n<div id=\"element-body-14\">\n<p>Apenas trascendi\u00f3 la muerte de Mi\u00f1o, la mujer lleg\u00f3 hasta el predio del ex Batall\u00f3n de Log\u00edstica y desbloque\u00f3 el tel\u00e9fono de quien hab\u00eda sido su pareja hasta hac\u00eda unas pocas horas. All\u00ed los investigadores constataron que <strong>una de las \u00faltimas b\u00fasquedas que realiz\u00f3 en Google fue sobre las formas de quitarse la vida<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-16\">\n<p>Fuentes vinculadas a la causa dijeron que una semana antes el soldado hab\u00eda estado en ese predio junto a otros militares realizando tareas de limpieza y se hab\u00eda tomado fotos en la torre donde finalmente puso fin a su vida.<\/p>\n<\/div>\n<div id=\"element-body-17\">\n<p>El tanque de agua de lo que fue el predio del Batall\u00f3n de Log\u00edstica del Ej\u00e9rcito Argentino en Curuz\u00fa Cuati\u00e1 ya fue escenario de <strong>cuatro suicidios<\/strong>. <\/p>\n<\/div>\n<div id=\"element-body-18\">\n<p>El lugar no cuenta con cerco perimetral y todos los intentos de la fuerza por evitar el ingreso de civiles resultaron vanos. Cuenta con calles internas asfaltadas y es por eso que muchas personas que viven en la zona rural las utilizan para acortar camino cuando se dirigen hacia la ciudad.<\/p>\n<\/div>\n<div id=\"element-body-19\">\n<p>Fuentes judiciales dijeron que no se hall\u00f3 ning\u00fan indicio que revele la participaci\u00f3n de terceros en la muerte de Mi\u00f1o. Es por eso que, una vez finalizada la autopsia, el cuerpo fue entregado a sus familiares para la inhumaci\u00f3n.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/policiales\/tanque-horror-predio-abandonado-ejercito-suicidios-soldado_0_CfZXreyrN5.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un soldado voluntario del Ej\u00e9rcito fue encontrado muerto en un predio militar abandonado, en Curuz\u00fa Cuati\u00e1, Corrientes. \u201cMe denunciaste, voy a tener problemas en el Ej\u00e9rcito\u201d, fue el \u00faltimo mensaje que le envi\u00f3 a su ex novia, quien hab\u00eda decidido cortar el v\u00ednculo unas horas antes y realiz\u00f3 una exposici\u00f3n ante la Comisar\u00eda de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1932,2606,351,23285,23208],"class_list":["post-46797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-cuatro","tag-ellos","tag-entre","tag-soldado","tag-suicidios"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46797"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46798"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}