{"id":46758,"date":"2025-07-31T10:10:03","date_gmt":"2025-07-31T13:10:03","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/la-ciudad-desalojo-un-predio-de-palermo-en-el-que-funcionaba-una-cooperativa-k\/"},"modified":"2025-07-31T10:10:03","modified_gmt":"2025-07-31T13:10:03","slug":"la-ciudad-desalojo-un-predio-de-palermo-en-el-que-funcionaba-una-cooperativa-k","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/la-ciudad-desalojo-un-predio-de-palermo-en-el-que-funcionaba-una-cooperativa-k\/","title":{"rendered":"La Ciudad desaloj\u00f3 un predio de Palermo en el que funcionaba una cooperativa K"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/La-Ciudad-desalojo-un-predio-de-Palermo-en-el-que.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>El Gobierno de la Ciudad desaloj\u00f3 este jueves un <strong>predio en Palermo<\/strong> en el que funcionaba un centro cultural del movimiento La Dignidad. &#8220;Hace m\u00e1s de 20 a\u00f1os estaba tomado&#8221;, indicaron fuentes porte\u00f1as, que tambi\u00e9n asociaron la organizaci\u00f3n piquetera a Juan Grabois. Sin embargo, desde el movimiento social aseguraron que all\u00ed funciona un comedor comunitario con habilitaci\u00f3n del propio Gobierno porte\u00f1o, que les entrega mercader\u00eda todos los d\u00edas, y adjudicaron el desalojo a cuestiones pol\u00edticas.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>El predio desalojado se encuentra detr\u00e1s del Mercado de Bonpland 1660 y, seg\u00fan inform\u00f3 el Gobierno de la Ciudad, se suma a otros 375 inmuebles recuperados desde el comienzo de la gesti\u00f3n de Jorge Macri. Durante el operativo, tambi\u00e9n <strong>detuvieron a un supuesto empleado del lugar que &#8220;ten\u00eda orden de captura&#8221;.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>&#8220;Ahora los comerciantes del Mercado, que no tienen relaci\u00f3n con la organizaci\u00f3n de Grabois, podr\u00e1n trabajar con normalidad. Adem\u00e1s, la Ciudad dej\u00f3 de financiar los colectivos que trasladaban desde el Conurbano a los cartoneros de cooperativas ligadas al dirigente&#8221;, destacaron desde Ciudad.<\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>Rafael Klejzer, dirigente del Movimiento Popular La Dignidad, habl\u00f3 con <strong>Clar\u00edn <\/strong>y asegur\u00f3 que el movimiento social hace uso del predio hace 20 a\u00f1os gracias a una sesi\u00f3n por parte del Gobierno porte\u00f1o. &#8220;Funciona como comedor comunitario y teatro&#8221;, detall\u00f3.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>En ese sentido, destac\u00f3 que &#8220;todos los d\u00edas nos llega mercader\u00eda para 300 personas&#8221;. Esa mercader\u00eda es entregada por el ministerio de Desarrollo Humano de la Ciudad a diario, a las 7 de la ma\u00f1ana, detall\u00f3.<\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>Adem\u00e1s, rechaz\u00f3 la vinculaci\u00f3n de La Dignidad con Grabois, como hab\u00eda sostenido el Gobierno porte\u00f1o. Klejzer aclar\u00f3 que el dirigente de Patria Grande hace tiempo est\u00e1 alejado de ese movimiento social y que mantienen &#8220;una relaci\u00f3n fraternal&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>Respecto del hombre detenido, Klejzer asegur\u00f3 que no saben qui\u00e9n es y rechaz\u00f3 que se trate de un empleado de la cooperativa. &#8220;El espacio estaba cerrado porque eran las 6 de la ma\u00f1ana cuando desalojaron&#8221;, indic\u00f3.<\/p>\n<\/div>\n<div id=\"element-body-9\">\n<p>Se trata de un comedor comunitario asistido por el Gobierno de la Ciudad, que cuenta tambi\u00e9n con un espacio teatral. <strong>Se encuentra habilitado para ambas cuestiones <\/strong>y la cooperativa paga los impuestos correspondientes, indicaron. &#8220;Hace 20 a\u00f1os la Ciudad nos legaliza mandando alimentos&#8221;, asever\u00f3 Klejzer.<\/p>\n<\/div>\n<div id=\"element-body-10\">\n<p>Antes de las 10 de la ma\u00f1ana, el secretario de Seguridad porte\u00f1o, <strong>Maximiliano Pi\u00f1eiro<\/strong>, habl\u00f3 con los medios presentes en el predio y se\u00f1al\u00f3 que, seg\u00fan los vecinos de Palermo, los fines de semana se realizaban fiestas en el lugar.<\/p>\n<\/div>\n<div id=\"element-body-11\">\n<p><strong>&#8220;El lugar estaba usurpado desde 2012,<\/strong> que se venci\u00f3 y nadie la renov\u00f3. No funcionaba un comedor comunitario, hac\u00edan fiestas&#8221;, marc\u00f3 Pi\u00f1eiro y se\u00f1al\u00f3 adem\u00e1s que en el desalojo encontraron banderas y otros elementos para &#8220;piquetes&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-12\">\n<div class=\"sc-c2c2a3c6-1 kQhBlc videoText videoText\">\n<h2>Video<\/h2>\n<p>Una mujer del Movimiento Popular La Dignidad contradijo al Gobierno porte\u00f1o y asegur\u00f3 que el predio de Palermo estaba habilitado<\/p>\n<\/div>\n<\/div>\n<div id=\"element-body-13\">\n<p>La conferencia de prensa fue interrumpida en un momento por una mujer que se presume forma parte de La Dignidad y llevaba consigo un papel con la habilitaci\u00f3n del comedor comunitario. Seg\u00fan dijo, el predio est\u00e1 habilitado y funciona como un centro cultural.<strong> &#8220;Usted est\u00e1 mintiendo, est\u00e1 desinformando&#8221;<\/strong>, acus\u00f3 al secretario porte\u00f1o. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/politica\/ciudad-desalojo-predio-palermo-funcionaba-cooperativa-k_0_1anxZPXUdG.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de la Ciudad desaloj\u00f3 este jueves un predio en Palermo en el que funcionaba un centro cultural del movimiento La Dignidad. &#8220;Hace m\u00e1s de 20 a\u00f1os estaba tomado&#8221;, indicaron fuentes porte\u00f1as, que tambi\u00e9n asociaron la organizaci\u00f3n piquetera a Juan Grabois. Sin embargo, desde el movimiento social aseguraron que all\u00ed funciona un comedor comunitario [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[984,3260,11023,22098,722,9867,73],"class_list":["post-46758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-ciudad","tag-cooperativa","tag-desalojo","tag-funcionaba","tag-palermo","tag-predio","tag-una"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46758"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46759"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}