{"id":46716,"date":"2025-07-31T06:28:28","date_gmt":"2025-07-31T09:28:28","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/jujuy-apuesta-a-desarrollar-la-mineria-mas-alla-del-litio\/"},"modified":"2025-07-31T06:28:28","modified_gmt":"2025-07-31T09:28:28","slug":"jujuy-apuesta-a-desarrollar-la-mineria-mas-alla-del-litio","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/jujuy-apuesta-a-desarrollar-la-mineria-mas-alla-del-litio\/","title":{"rendered":"Jujuy apuesta a desarrollar la miner\u00eda m\u00e1s all\u00e1 del litio"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/Jujuy-apuesta-a-desarrollar-la-mineria-mas-alla-del-litio.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>Jujuy, la provincia que m\u00e1s litio produce en el pa\u00eds, puso en marcha un<strong> mapeo estrat\u00e9gico <\/strong>para establecer qu\u00e9 otros minerales pueden extraerse en las distintas regiones de su territorio.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>Aunque el litio ha sido denominado el <strong>&#8220;oro blanco&#8221; <\/strong>por su papel clave en la fabricaci\u00f3n de bater\u00edas el\u00e9ctricas, en los \u00faltimos a\u00f1os este auge ha comenzado a perder fuerza. Esto se debe a que la <strong>transici\u00f3n energ\u00e9tica<\/strong> que pondr\u00eda fin a los autos a combusti\u00f3n en Europa se viene demorando por razones geopol\u00edticas y econ\u00f3micas, lo que hizo bajar el precio internacional del litio.<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>Con el objetivo de promover la inversi\u00f3n minera la empresa provincial Jujuy Energ\u00eda y Miner\u00eda Sociedad del Estado (JEMSE) est\u00e1 coordinando <strong>un proyecto estrat\u00e9gico de prospecci\u00f3n y evaluaci\u00f3n de \u00e1reas mineras.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p>Esta semana se present\u00f3 en el Cabildo de Jujuy un mapeo del potencial geol\u00f3gico de las \u00e1reas administradas por JEMSE. &#8220;<strong>Queremos que el mundo conozca nuestro potencial en miner\u00eda de la manera m\u00e1s precisa posible para que m\u00e1s empresas nos puedan elegir y as\u00ed haya m\u00e1s trabajo para nuestra gente<\/strong>&#8220;, sostuvo en ese evento el gobernador Carlos Sadir.<\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p><strong>&#8220;La miner\u00eda es el sector productivo m\u00e1s pujante de la provincia&#8221;<\/strong>, apunt\u00f3 Ezequiel Lello, presidente de JEMSE. &#8220;Jujuy es conocida por el litio, pero tenemos diversidad y riqueza de recursos. Queremos seguir ampliando la cantidad de proyectos que tenemos en la provincia. El sector minero vive de la exploraci\u00f3n y no de la explotaci\u00f3n. <strong>El rol del Estado para generar datos precompetitivos es clave para este desarrollo<\/strong>&#8220;.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>El mapeo se realiz\u00f3 sobre 8 clusters distribuidos en la provincia, aunque la mayor parte est\u00e1 concentrada en La Puna. Las anomal\u00edas geof\u00edsicas que descubren en esa exploraci\u00f3n son indicios de que podr\u00eda haber vetas aptas para la producci\u00f3n minera. <strong>Adem\u00e1s de litio hay potencial para nuevas explotaciones de oro, plata, geotermia, cobre y &#8220;tierras raras&#8221;.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>&#8220;El ciclo minero empieza con prospecci\u00f3n, luego vienen tres niveles de exploraci\u00f3n y ah\u00ed se decide si se avanza con el proyecto. Con esto <strong>se busca reducir el riesgo y la incertidumbre geol\u00f3gica<\/strong>&#8220;, se\u00f1al\u00f3 Julio Matteo Bruna Novillo, presidente del Servicio Geol\u00f3gico Minero Argentino (SEGEMAR).<\/p>\n<\/div>\n<div id=\"element-body-7\">\n<p>En el acto se firm\u00f3 una Carta de Intenci\u00f3n entre SEGEMAR y la Gobernaci\u00f3n de Jujuy, que dar\u00e1 inicio a un <strong>segundo proyecto <\/strong>conjunto con JEMSE enfocado en la sistematizaci\u00f3n de informaci\u00f3n geol\u00f3gico-ambiental. <\/p>\n<\/div>\n<div id=\"element-body-9\">\n<p>En el 2023 las exportaciones mineras de la provincia superaron los <strong>US$ 900 millones y representan el 7% del producto, <\/strong>seg\u00fan detall\u00f3 el secretario de Miner\u00eda Jose Gabriel G\u00f3mez. Hay 17 empresas trabajando all\u00ed. &#8220;En los \u00faltimos cinco da\u00f1os venimos aumentando considerablemente el presupuesto de exploraci\u00f3n. <strong>Hasta ahora estaba muy enfocado en litio y hoy queremos fomentar la miner\u00eda metal\u00edfera donde tenemos un gran potencial&#8221;.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-10\">\n<p>&#8220;Hay indicios de que habr\u00eda &#8220;tierras raras&#8221;, que son minerales que se utilizan en todos los nuevos circuitos el\u00e9ctricos. Por la carrera tecnol\u00f3gica que hay en el mundo<strong> las &#8220;tierras raras&#8221; van a ser un mineral muy preciado en los pr\u00f3ximos diez a\u00f1os.<\/strong> Ya hay dos empresas en una prospecci\u00f3n inicial tomando muestras para ver cu\u00e1l ser\u00eda el potencial&#8221;, explic\u00f3 G\u00f3mez. <\/p>\n<\/div>\n<div id=\"element-body-11\">\n<p>En la miner\u00eda juje\u00f1a China\u00a0es uno de los principales inversores, con presencia a trav\u00e9s de dos compa\u00f1\u00edas Exar, donde tambi\u00e9n el JEMAR tiene una participaci\u00f3n, y CNGR Argentina.<\/p>\n<\/div>\n<div id=\"element-body-12\">\n<p>&#8220;Tenemos muy buenas perspectivas. Estamos trabajando muy fuertemente este a\u00f1o con el objetivo de alcanzar entre 30 y 35.000 toneladas de carbonato de litio. <strong>Y ya el a\u00f1o que viene queremos alcanzar nuestra m\u00e1xima capacidad instalada, que es de 40.000 toneladas&#8221;,<\/strong> comentaron desde Exar. La inversi\u00f3n total de la compa\u00f1\u00eda supera los<strong> US$ 1.000 millones <\/strong>desde que se inici\u00f3 la construcci\u00f3n de la planta en 2018. <\/p>\n<\/div>\n<div id=\"element-body-13\">\n<p>Actualmente, el proyecto cuenta con m\u00e1s de 2.100 colaboradores, de los cuales m\u00e1s del 60% reside en Jujuy.<\/p>\n<\/div>\n<div id=\"element-body-14\">\n<p>Nicol\u00e1s Damin, Director de Asuntos P\u00fablicos LATAM de CNGR, coment\u00f3 que compraron los proyectos de litio en Jama y Solaroz, previamente en manos de otras compa\u00f1\u00edas. &#8220;La compra de las dos empresas demand\u00f3 <strong>US$ 150 millones <\/strong>y las campa\u00f1as de perforaci\u00f3n que est\u00e1n haciendo ahora duplican ese monto&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-15\">\n<p>Uno de los puntos sobre los que trabajan fuerte las mineras es el <strong>consenso social.<\/strong> &#8220;El proyecto es de participaci\u00f3n plena de los trabajadores de las comunidades y con los referentes de la provincia y con el sindicato. Adem\u00e1s todas  las empresas mineras tenemos monitoreos ambientales participativos, con miembros de las comunidades y de ONGs y de y del CONICET y del Gobierno para verificar todo el impacto ambiental, ya sea flora, fauna, el agua y por supuesto las personas&#8221;, agreg\u00f3 Damin. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/economia\/jujuy-apuesta-desarrollar-mineria-alla-litio_0_nMr05NqADP.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jujuy, la provincia que m\u00e1s litio produce en el pa\u00eds, puso en marcha un mapeo estrat\u00e9gico para establecer qu\u00e9 otros minerales pueden extraerse en las distintas regiones de su territorio. Aunque el litio ha sido denominado el &#8220;oro blanco&#8221; por su papel clave en la fabricaci\u00f3n de bater\u00edas el\u00e9ctricas, en los \u00faltimos a\u00f1os este auge [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[7642,2599,100,12289,11805,4621,155,10529],"class_list":["post-46716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-alla","tag-apuesta","tag-del","tag-desarrollar","tag-jujuy","tag-litio","tag-mas","tag-mineria"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46716"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46717"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}