{"id":46666,"date":"2025-07-30T20:36:59","date_gmt":"2025-07-30T23:36:59","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/la-primera-para-milei-la-tercera-para-el-peronismo-y-la-incognita-por-los-gritos-de-grabois\/"},"modified":"2025-07-30T20:36:59","modified_gmt":"2025-07-30T23:36:59","slug":"la-primera-para-milei-la-tercera-para-el-peronismo-y-la-incognita-por-los-gritos-de-grabois","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/la-primera-para-milei-la-tercera-para-el-peronismo-y-la-incognita-por-los-gritos-de-grabois\/","title":{"rendered":"La Primera para Milei, la Tercera para el peronismo y la inc\u00f3gnita por los gritos de Grabois"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/La-Primera-para-Milei-la-Tercera-para-el-peronismo-y.jpg\" \/><\/p>\n<div id=\"element-body-2\">\n<p>Tres horas de asado con vista al r\u00edo fueron el marco de la primera reuni\u00f3n, en mucho tiempo, donde el peronismo no se desangr\u00f3. Con el objetivo de repasar c\u00f3mo ser\u00e1 la pelea electoral en la Primera Secci\u00f3n Electoral el pr\u00f3ximo 7 de septiembre, el gobernado<strong>r Axel Kicillof viaj\u00f3 de La Plata hasta San Fernando para encontrarse con Sergio Tom\u00e1s Massa<\/strong>, quien fue anfitri\u00f3n como dirigente de esa secci\u00f3n y como jefe pol\u00edtico del intendente local Juan Andreotti, y con los intendentes y candidatos de esa zona.<\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p><strong>Kicillof estuvo escoltado por su ministro Gabriel Katopodis<\/strong>, quien particip\u00f3 en el cierre de listas para la elecci\u00f3n bonaerense en nombre del kicillofismo, junto al jefe de Gabinete provincial Carlos Bianco. Alrededor de la mesa, y \u00e1vidos de una porci\u00f3n de vac\u00edo, estuvieron tambi\u00e9n <strong>los alcaldes Ariel Sujarchuk, Fernando Moreira, Pablo Descalzo y los cristinistas Dami\u00e1n Selci, Mariel Fern\u00e1ndez, Juan Ustarroz, Gustavo Men\u00e9ndez<\/strong>, Leonardo Nardini, as\u00ed como el inoxidable Mario Ishii, en su doble condici\u00f3n de intendente y candidato testimonial a concejal.<\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>Tambi\u00e9n estaban los primeros candidatos a concejales de los distritos donde el peronismo no gobierna en esa secci\u00f3n y el \u00fanico ausente fue el pilarense Federico Achaval, con aviso y sin problema pol\u00edtico alguno. Luego de una larga introducci\u00f3n del gobernador, se abund\u00f3 en que &#8220;hay que plebiscitar Milei s\u00ed o Milei no&#8221; pero conscientes de que en la Primera, el peronismo no gana hace mucho tiempo.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>&#8220;La Primera va a ser de Valenzuela&#8221;, dijo uno de los intendentes que no profesan afecto con el actual intendente de Tres de Febrero, el historiador y economista Diego Valenzuela que emigr\u00f3 de las filas del PRO, se muestra cercan\u00edsimo a Patricia Bullrich y que profesa una relaci\u00f3n de amistad con el hoy presidente Javier Gerardo Milei desde los tiempos universitarios. Ese v\u00ednculo personal se transformar\u00e1 en pol\u00edtico en pocos d\u00edas cuando<strong> el jefe de Estado se muestre en tierras conurbanas junto al primer candidato a senador provincial de la Primera,  en un desembarco fiel al estilo mile\u00edsta<\/strong> y con la coordinaci\u00f3n f\u00e9rrea de Karina Elizabeth Milei. <em>Fuerzas del cielo&#8230;<\/em><\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>Otro tema que form\u00f3 parte de la cumbre peronista de este martes fue el por qu\u00e9 de la ofensiva de esta semana de <strong>Juan Grabois. El dirigente de la UTEP es apreciado tanto por Cristina como por M\u00e1ximo Kirchner<\/strong> pero sus \u00faltimas palabras dur\u00edsimas contra Sergio Massa <strong>sorprendieron hasta en el departamento de San Jos\u00e9 1111<\/strong>, donde se encuentra cumpliendo prisi\u00f3n domiciliaria la ex Presidenta de la Naci\u00f3n.<\/p>\n<\/div>\n<div id=\"element-body-9\">\n<p>\u201cNo puedo aceptar d\u00f3cilmente que el espacio peronista hoy a r\u00edo revuelto lo hegemonice Sergio Massa, alguien que le hizo da\u00f1o a Jorge Bergoglio&#8230; no queremos permitir que una persona que pertenece, para nosotros, a la derecha del peronismo y su ala liberal sea hoy la que hegemoniza la cosa y publica los spots&#8221;, dijo con detalle Grabois, a sabiendas de que el tigrense es quien ha difundido las primeras im\u00e1genes proselitistas de &#8220;Fuerza Patria&#8221;, la nueva denominaci\u00f3n del peronismo, que dej\u00f3 atr\u00e1s el nombre de &#8220;Frente de Todos&#8221; o &#8220;Uni\u00f3n por la Patria&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-10\">\n<p>Las razones de la andanada del ex colaborador del Papa Francisco son interpretadas de distintos modos: en su campamento, dicen que es una disputa pol\u00edtica con la que &#8220;le hablan&#8221; a la gente ap\u00e1tica que, incluso, puede no tener ganas hoy de ir a votar en las elecciones bonaerenses del 7 de septiembre. Y que al no haber PASO (Primarias), el modo de diferenciarse es de este modo. Y que si no se oponen a que Massa sea el candidato a diputado nacional en las elecciones de octubre,<strong> &#8220;vamos a un nuevo Alberto Fern\u00e1ndez&#8221;, seg\u00fan uno de los seguidores de Grabois.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-11\">\n<p>En la reuni\u00f3n de San Fernando hab\u00eda molestias con los dichos del dirigente social pero se pusieron de acuerdo en no contestarle, m\u00e1s all\u00e1 del duro tuit de Sebasti\u00e1n Galmarini, cu\u00f1ado de Massa y militante del Frente Renovador. <strong>&#8220;El Gobierno lo debe tener agarrado con algo, por eso nos pega&#8221;, rezong\u00f3 uno de los presentes en la cita.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-12\">\n<p>Tambi\u00e9n se habl\u00f3 de encuestas donde<strong> el peronismo da por descontado que Valenzuela y LLA m\u00e1s el PRO ganar\u00e1n en la Primera Secci\u00f3n pero apuestan a que la elecci\u00f3n en la Tercera Secci\u00f3n sea la que marque una diferencia a favor<\/strong> que los lleve a pelear la elecci\u00f3n a nivel provincial. <em>De esperanzas se vive&#8230;<\/em><\/p>\n<\/div>\n<div id=\"element-body-15\">\n<p>En el asado peronista se desglosaron <strong>mediciones propias del peronismo, que llegan incluso hasta el departamento de Cristina Kirchner, quien funciona pol\u00edticamente como cuando estaba instalada en el Instituto Patria<\/strong>, solo que ahora por tel\u00e9fono o de modo virtual. CFK devora esas encuestas.<\/p>\n<\/div>\n<div id=\"element-body-16\">\n<p>Uno de los puntos que se hablaron entre tira y tira de asado, se dijo que<strong> &#8220;Milei est\u00e1 en su peor momento&#8221; desde que es gobierno en la Provincia. <\/strong>Que mide mejor en la S\u00e9ptima Secci\u00f3n y que retiene votos de j\u00f3venes y jubilados y lo que es el voto tradicionalmente antiperonista. Adem\u00e1s, de personas que contestan que &#8220;yo quiero que a Milei le vaya bien&#8221;, m\u00e1s all\u00e1 de su situaci\u00f3n econ\u00f3mica personal.<\/p>\n<\/div>\n<div id=\"element-body-17\">\n<p>Aunque el tema de que muchos ciudadanos bonaerenses no tienen idea de que hay que votar en septiembre, hay un rasgo que no ser\u00eda favorable al Gobierno nacional: el ausentismo en la provincia de Buenos Aires lo estar\u00eda afectando a Milei, por ser que <strong>&#8220;j\u00f3venes varones pobres&#8221; los que no le prestar\u00edan ninguna atenci\u00f3n a la elecci\u00f3n bonaerense de septiembre<\/strong>. <em>Cuesti\u00f3n de n\u00fameros&#8230;<\/em><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/politica\/primera-milei-tercera-peronismo-incognita-gritos-grabois_0_C8JM8UkYVI.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tres horas de asado con vista al r\u00edo fueron el marco de la primera reuni\u00f3n, en mucho tiempo, donde el peronismo no se desangr\u00f3. Con el objetivo de repasar c\u00f3mo ser\u00e1 la pelea electoral en la Primera Secci\u00f3n Electoral el pr\u00f3ximo 7 de septiembre, el gobernador Axel Kicillof viaj\u00f3 de La Plata hasta San Fernando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12871,6450,19831,28,77,16,1455,142,89,1059],"class_list":["post-46666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-grabois","tag-gritos","tag-incognita","tag-los","tag-milei","tag-para","tag-peronismo","tag-por","tag-primera","tag-tercera"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46666"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46667"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}