{"id":46662,"date":"2025-07-30T20:27:59","date_gmt":"2025-07-30T23:27:59","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/boca-revelo-como-seran-las-reformas-de-la-bombonera-en-medio-de-la-crisis-deportiva\/"},"modified":"2025-07-30T20:27:59","modified_gmt":"2025-07-30T23:27:59","slug":"boca-revelo-como-seran-las-reformas-de-la-bombonera-en-medio-de-la-crisis-deportiva","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/boca-revelo-como-seran-las-reformas-de-la-bombonera-en-medio-de-la-crisis-deportiva\/","title":{"rendered":"Boca revel\u00f3 c\u00f3mo ser\u00e1n las reformas de la Bombonera, en medio de la crisis deportiva"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/Boca-revelo-como-seran-las-reformas-de-la-Bombonera-en.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>Mientras el club atraviesa su <strong>peor<\/strong> <strong>racha <\/strong>futbol\u00edstica de la gesti\u00f3n <strong>Riquelme<\/strong>, el proyecto <em>de <\/em><strong>ampliaci\u00f3n <\/strong>anuncia <strong>nuevas modificaciones<\/strong> en las zonas externas del <strong>Alberto J. Armando<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>Desde el club, revelaron las <strong>im\u00e1genes <\/strong>presentadas por el equipo de arquitectos, es la <strong>\u00faltima etapa de reformas<\/strong> previo al anuncio de su <strong>ampliaci\u00f3n<\/strong>. Habr\u00e1 <strong>nuevos ingresos<\/strong> para los futbolistas y el port\u00f3n de ingreso &#8211;<em>por el que hacen su arribo los micros de jugadores y delegaciones<\/em>&#8211; contiguo a la cancha de bochas, ser\u00e1 reparado durante las pr\u00f3ximas semanas. Tambi\u00e9n se agregar\u00e1n ingresos m\u00e1s amplios y una <strong>pantalla led<\/strong> en la puerta principal.<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>Adem\u00e1s, se agregar\u00e1n otros <strong>dos elevadores<\/strong> en la <strong>Puerta 18<\/strong> -donde actualmente s\u00f3lo hay dos- y se construir\u00e1n un total de <strong>16 ascensores<\/strong> sobre la zona de v\u00edas que van en paralelo a la calle Irala, por donde ingresar\u00e1n los socios que concurran a las <strong>plateas medias y altas.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>Dentro de las reformas de la <strong>Platea Baja<\/strong>, se encuentra un <strong>nuevo patio de comidas<\/strong> que se empezar\u00e1 a construir en septiembre u octubre. Tambi\u00e9n se ampliar\u00e1 el pasillo de acceso y se construir\u00e1n <strong>nuevos ba\u00f1os<\/strong> con la intenci\u00f3n de <strong>cubrir la capacidad<\/strong> de dicho sector, que es de <strong>aproximadamente 4 mil personas<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>Las nuevas modificaciones en el exterior del club tambi\u00e9n incluyen el <strong>play\u00f3n de estacionamiento<\/strong> y la <strong>luminaria<\/strong>. En el play\u00f3n que se ubica a la par de las v\u00edas del tren, se ganar\u00e1n al rededor de <strong>400 lugares<\/strong> &#8211;<em>aunque ya se piensa en construir <\/em><strong><em>1000 m\u00e1s<\/em><\/strong>&#8211; y se completar\u00e1 el <strong>techado<\/strong> en el mes de <strong>Septiembre<\/strong>. Adem\u00e1s, se instalaron <strong>200 nuevos reflectores<\/strong> y se realiz\u00f3 el hormigonado. La nueva luminaria, ser\u00e1 de gran ayuda tanto en d\u00edas de partido, como en el d\u00eda a d\u00eda de los vecinos de alrededores cuando no hay f\u00fatbol.<\/p>\n<\/div>\n<div id=\"element-body-7\">\n<p>La remodelaci\u00f3n tambi\u00e9n lleg\u00f3 a <strong>Boca Predio<\/strong>. Se construir\u00e1 una <strong>cancha de c\u00e9sped sint\u00e9tico techada<\/strong>, destinada exclusivamente al <strong>trabajo f\u00edsico de los juveniles <\/strong><em>-haciendo foco en d\u00edas de lluvias o tormentas-<\/em> y <strong>otra al aire libre<\/strong>. Tambi\u00e9n se levantar\u00e1 <strong>un hotel<\/strong> con capacidad para <strong>150 personas<\/strong> que ser\u00e1 destinado al plantel <strong>profesional <\/strong>y la <strong>Reserva<\/strong>, con el objetivo de <strong>evitar los costos<\/strong> y las dificultades de la hoteler\u00eda en temporadas altas.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/deportes\/boca-revelo-reformas-bombonera-medio-crisis-deportiva_0_fW2KJgX9IC.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras el club atraviesa su peor racha futbol\u00edstica de la gesti\u00f3n Riquelme, el proyecto de ampliaci\u00f3n anuncia nuevas modificaciones en las zonas externas del Alberto J. Armando. Desde el club, revelaron las im\u00e1genes presentadas por el equipo de arquitectos, es la \u00faltima etapa de reformas previo al anuncio de su ampliaci\u00f3n. Habr\u00e1 nuevos ingresos para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[707,3132,66,625,8283,48,1224,4576,241,551],"class_list":["post-46662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-boca","tag-bombonera","tag-como","tag-crisis","tag-deportiva","tag-las","tag-medio","tag-reformas","tag-revelo","tag-seran"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46662"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46663"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}