{"id":46655,"date":"2025-07-30T20:15:56","date_gmt":"2025-07-30T23:15:56","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/por-que-y-que-espera-el-mercado-de-cara-a-las-elecciones\/"},"modified":"2025-07-30T20:15:56","modified_gmt":"2025-07-30T23:15:56","slug":"por-que-y-que-espera-el-mercado-de-cara-a-las-elecciones","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/por-que-y-que-espera-el-mercado-de-cara-a-las-elecciones\/","title":{"rendered":"por qu\u00e9 y qu\u00e9 espera el mercado de cara a las elecciones"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/03\/escalan-los-dolares-alternativos-y-sube-el-riesgo-pais-mientras.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>La sensaci\u00f3n de calma en el mercado cambiario en la primera parte del a\u00f1o acompa\u00f1\u00f3 al crecimiento de los pr\u00e9stamos en d\u00f3lares en los bancos. La din\u00e1mica de las empresas que eligen financiarse en moneda extranjera se encuadra en un proceso de expansi\u00f3n del cr\u00e9dito a nivel general. Sin embargo, en la city advierten que la suba de tasas podr\u00eda repercutir directamente en la financiaci\u00f3n.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>Seg\u00fan datos del Banco Central reportados por la consultora Delphos. actualmente el stock de pr\u00e9stamos en d\u00f3lares <strong>supera los US$ 16.700 millones, nivel que se ubica por encima del \u00faltimo pico alcanzado en 2018, cuando hab\u00eda llegado a los US$ 16.212 millones.<\/strong> Este nivel <strong>es el m\u00e1s alto para el financiamiento en moneda extranjera en las \u00faltimas dos d\u00e9cadas.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>&#8220;Este hito refuerza la recuperaci\u00f3n del sistema financiero, particularmente del cr\u00e9dito, que emerge como uno de los grandes beneficiarios del nuevo modelo econ\u00f3mico&#8221;, destacaron en Delphos. &#8220;El sector de intermediaci\u00f3n financiera lo refleja con claridad: el EMAE sectorial ya se ubica un 10% por encima del m\u00e1ximo de 2023 y en niveles no vistos desde septiembre de 2018. Esta recomposici\u00f3n tambi\u00e9n se ve en las series de pr\u00e9stamos, tanto en d\u00f3lares como en pesos&#8221;, remarcaron la consultora. <\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p>Mientras que el cr\u00e9dito en d\u00f3lares marca r\u00e9cords no vistos en dos d\u00e9cadas, los pr\u00e9stamos en pesos aumentan a un ritmo del 80% anual por encima de la inflaci\u00f3n.&#8221;Su bien los pr\u00e9stamos en pesos muestran una recuperaci\u00f3n veloz, todav\u00eda se encuentran un 20% por debajo de los m\u00e1ximos de 2018 en t\u00e9rminos reales&#8221;, resaltaron en Delphos.<\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>Para Guillermo Barbero, de First Capital Market, la din\u00e1mica de los pr\u00e9stamos en d\u00f3lares corre por un carril distinto de la financiaci\u00f3n en pesos. &#8220;En lo que va del a\u00f1o, las variaciones de pr\u00e9stamos al sector privado, sacando las familias, fueron &#8220;complementarias&#8221;, trato de explicar: si suben bastante los pr\u00e9stamos en pesos, lo pr\u00e9stamos en d\u00f3lares suben poco, y viceversa. Cuando suben los dos rubros, suben de manera moderada&#8221;, explic\u00f3.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>En un banco privado coincidieron con el an\u00e1lisis: &#8220;Los pr\u00e9stamos financieros en d\u00f3lares para empresas muestran un comportamiento de crecimiento sostenido sobre los pr\u00e9stamos en moneda local, esto se da principalmente por la volatilidad de tasas de intereses para financiaciones en pesos y la proyecci\u00f3n de estabilidad cambiaria&#8221;. <\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>En la entidad a\u00f1adieron que, por el contrario, y pese a los anuncios del Gobierno para captar los d\u00f3lares del colch\u00f3n, no hubo movimientos significativos en el nivel de d\u00f3lares depositados en los bancos. Al viernes pasado, \u00faltimo dato disponible en el Banco Central, los d\u00f3lares del sector privado totalizaban los US$ 32.801 millones, unos US$ 800 millones m\u00e1s de lo registrado antes de la salida del cepo.<\/p>\n<\/div>\n<div id=\"element-body-7\">\n<p>El movimiento reciente del d\u00f3lar y la suba de tasas para intentar contenerlo pueden afectar esta din\u00e1mica. Por un lado, en Delphos apuntaron que &#8220;Las tasas reales elevadas, derivadas de la actual pol\u00edtica monetaria contractiva, representan un posible obst\u00e1culo, pero si no se convierten en una barrera estructural, alcanzar esos m\u00e1ximos parece solo una cuesti\u00f3n de tiempo&#8221;.<\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>Por su parte, Barbero se\u00f1al\u00f3: &#8220;Lo que tiene m\u00e1s impacto es la expectativa de devaluaci\u00f3n. Adem\u00e1s no hay que pasar por alto que los pr\u00e9stamos en d\u00f3lares se otorgan mayoritariamente a empresas que tengan una relaci\u00f3n con el comercio exterior y la generaci\u00f3n de divisas&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/economia\/credito-dolares-ubica-nivel-alto-ultimos-20-anos-espera-mercado-cara-elecciones_0_ys1HoJjeun.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sensaci\u00f3n de calma en el mercado cambiario en la primera parte del a\u00f1o acompa\u00f1\u00f3 al crecimiento de los pr\u00e9stamos en d\u00f3lares en los bancos. La din\u00e1mica de las empresas que eligen financiarse en moneda extranjera se encuadra en un proceso de expansi\u00f3n del cr\u00e9dito a nivel general. Sin embargo, en la city advierten que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2812,404,463,48,1955,142,286],"class_list":["post-46655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-cara","tag-elecciones","tag-espera","tag-las","tag-mercado","tag-por","tag-que"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46655"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/12856"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}