{"id":46610,"date":"2025-07-30T17:52:11","date_gmt":"2025-07-30T20:52:11","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/llaryora-desafia-otra-vez-a-milei-y-se-hace-cargo-de-obras-en-rutas-nacionales\/"},"modified":"2025-07-30T17:52:11","modified_gmt":"2025-07-30T20:52:11","slug":"llaryora-desafia-otra-vez-a-milei-y-se-hace-cargo-de-obras-en-rutas-nacionales","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/llaryora-desafia-otra-vez-a-milei-y-se-hace-cargo-de-obras-en-rutas-nacionales\/","title":{"rendered":"Llaryora desaf\u00eda otra vez a Milei y se hace cargo de obras en rutas nacionales"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/Llaryora-desafia-otra-vez-a-Milei-y-se-hace-cargo.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>El gobernador de C\u00f3rdoba, <strong>Mart\u00edn Llaryora,<\/strong> volvi\u00f3 a desafiar al gobierno de Javier Milei y anunci\u00f3 que la provincia se har\u00e1 cargo de finalizar la Autopista de la Ruta Nacional 19. <strong>\u201cC\u00f3rdoba vuelve a dar un paso adelante cuando la Naci\u00f3n se detiene\u201d<\/strong>, sostuvo en clave de sutil chicana.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>Llaryora explic\u00f3 que se trata de &#8220;una obra estrat\u00e9gica que lleva a\u00f1os postergada&#8221;.<strong> &#8220;Si el Gobierno nacional no quiere hacer la obra, la haremos nosotros&#8221;,<\/strong> a\u00f1adi\u00f3 el mandatario provincial.<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>La novedad se da a conocer en la misma semana que inform\u00f3 tambi\u00e9n un aumento del 84,21% para los jubilaciones m\u00ednimas de la Caja Previsional cordobesa. En ese caso, precis\u00f3 que el incremento <strong>se har\u00e1 con los fondos que comenz\u00f3 a recibir del Ejecutivo nacional<\/strong>, luego del acuerdo alcanzado ante la Corte Suprema por la deuda previsional que manten\u00edan con la provincia.<\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p>El anuncio sobre la autov\u00eda fue realizado este mi\u00e9rcoles durante un acto en la capital provincial, en el que inform\u00f3 que la preadjudicaci\u00f3n significa que<strong> su administraci\u00f3n se har\u00e1 cargo de ejecutar los 62,9 kil\u00f3metros que faltan<\/strong> para completar el tramo entre las ciudades de San Francisco y C\u00f3rdoba.<\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>&#8220;De esta manera, nuestro Gobierno ratifica su compromiso de terminar esta infraestructura vial clave que, por ser una ruta nacional, es de competencia originaria del Estado nacional&#8221;, remarc\u00f3.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<blockquote class=\"twitter-tweet\">\n<p lang=\"es\" dir=\"ltr\">No se trata de una disputa pol\u00edtica, sino de una necesidad humana y productiva. Esta obra salva vidas y potencia el <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/desarrollo?src=hash&amp;ref_src=twsrc%5Etfw\">#desarrollo<\/a> regional. Agradezco a los intendentes de todos los partidos, a los representantes de los trabajadores y a cada comunidad por acompa\u00f1arnos. Esta es una\u2026 <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/t.co\/CwnQvGA8Hk\">pic.twitter.com\/CwnQvGA8Hk<\/a><\/p>\n<p>\u2014 Mart\u00edn Llaryora (@MartinLlaryora) <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/twitter.com\/MartinLlaryora\/status\/1950627645286166994?ref_src=twsrc%5Etfw\">July 30, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/politica\/cordoba-vuelve-dar-paso-adelante-nacion-detiene-llaryora-desafia-vez-milei-hace-cargo-obras-rutas-nacionales_0_xKpDOYBc00.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de C\u00f3rdoba, Mart\u00edn Llaryora, volvi\u00f3 a desafiar al gobierno de Javier Milei y anunci\u00f3 que la provincia se har\u00e1 cargo de finalizar la Autopista de la Ruta Nacional 19. \u201cC\u00f3rdoba vuelve a dar un paso adelante cuando la Naci\u00f3n se detiene\u201d, sostuvo en clave de sutil chicana. Llaryora explic\u00f3 que se trata de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[639,2573,1192,16422,77,2543,701,305,4560,111],"class_list":["post-46610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-cargo","tag-desafia","tag-hace","tag-llaryora","tag-milei","tag-nacionales","tag-obras","tag-otra","tag-rutas","tag-vez"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46610"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46611"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}