{"id":46579,"date":"2025-07-30T16:07:06","date_gmt":"2025-07-30T19:07:06","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/exfuncionario-de-macri-afirma-que-argentina-solo-podria-pagar-el-10-del-fallo-y-que-negociar-con-burford-seria-ilegal\/"},"modified":"2025-07-30T16:07:06","modified_gmt":"2025-07-30T19:07:06","slug":"exfuncionario-de-macri-afirma-que-argentina-solo-podria-pagar-el-10-del-fallo-y-que-negociar-con-burford-seria-ilegal","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/exfuncionario-de-macri-afirma-que-argentina-solo-podria-pagar-el-10-del-fallo-y-que-negociar-con-burford-seria-ilegal\/","title":{"rendered":"exfuncionario de Macri afirma que Argentina solo podr\u00eda pagar el 10% del fallo y que negociar con Burford &#8220;ser\u00eda ilegal&#8221;"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/exfuncionario-de-Macri-afirma-que-Argentina-solo-podria-pagar-el.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>El ex procurador del Tesoro de la Naci\u00f3n Bernardo Saravia Fr\u00edas -que trabaj\u00f3 durante el gobierno de Mauricio Macri- asegur\u00f3 este mi\u00e9rcoles ante los socios del Rotary Club de Buenos Aires que <strong>es &#8220;optimista&#8221; de que la Argentina pueda pagarle a los beneficiarios del fallo <\/strong>por la <strong>expropiaci\u00f3n de YPF <\/strong>mucho menos que los 16.100 millones de d\u00f3lares que determin\u00f3 la jueza estadounidense Loretta Preska.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>Saravia Fr\u00edas fue el abogado del Estado y llev\u00f3 adelante la defensa argentina en las etapas iniciales del caso que comenz\u00f3 en 2015, tuvo sentencia en septiembre de 2023 y todav\u00eda tiene derivaciones relevantes para la pol\u00edtica, en tanto corren por otros carriles apelaciones, procesos para descubrir m\u00e1s informaci\u00f3n y eventuales embargos.<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p><strong>El punto fundamental que argumenta el exfuncionario es que el fallo que benefici\u00f3 a Burford Capital<\/strong>, financiador de las demandas de Petersen Energ\u00eda, Petersen Energ\u00eda Inversora (las sociedades de la familia Eskenazi) y Eton Park, <strong>tiene un error garrafal: el tipo de cambio aplicable.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p>De acuerdo a la jurisprudencia estadounidense, sostiene Saravia Fr\u00edas, <strong>el tipo de cambio que se debi\u00f3 haber tomado fue el del momento en el que la Argentina tom\u00f3 control de YPF,<\/strong> el 7 de mayo de 2012 (cuando un d\u00f3lar equival\u00eda a $ 4,45), y <strong>no el de la sentencia, el 8 de septiembre de 2023 ($ 367,01).<\/strong><\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>De esa forma, y por la inestabilidad cambiaria argentina, el monto que calcul\u00f3 el exprocurador<strong> que deber\u00eda pagar el Estado es de aproximadamente 1.500 millones de d\u00f3lares, <\/strong>menos de un 10% del valor de la sentencia de Preska.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>Asimismo, Saravia Fr\u00edas remarc\u00f3 ante los socios del Rotary que esa es la clave para los representantes de la Argentina de cara a la Corte de Apelaciones de Nueva York, Estados Unidos, donde se discutir\u00e1 el fallo de fondo.<\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>Mientras tanto, dice, <strong>&#8220;no hay que sentarse a negociar&#8221; con Burford Capital porque &#8220;ser\u00eda ilegal&#8221;.<\/strong> El fondo contrat\u00f3 el a\u00f1o pasado a un grupo de tres argentinos encabezado por Gerardo Mato, ex HSBC, para negociar con los funcionarios argentinos y &#8220;sensibilizar&#8221; a actores influyentes sobre las implicancias del caso, pero el jefe de Gabinete, Guillermo Francos, le cerr\u00f3 la puerta a una negociaci\u00f3n.<\/p>\n<\/div>\n<div id=\"element-body-7\">\n<p><strong>&#8220;La Argentina tiene que reducir el monto de esta sentencia<\/strong>. Esos 16.100 millones de d\u00f3lares son una enormidad. Debemos mejorar nuestra posici\u00f3n negociadora, porque peor de lo que ya estamos no se puede. Pero tambi\u00e9n hay que cumplir las \u00f3rdenes de los jueces. Preska ya est\u00e1 furiosa con nosotros&#8221;, indic\u00f3 con su tonada salte\u00f1a Saravia Fr\u00edas en el Hotel Libertador.<\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>Y complet\u00f3: &#8220;Hay que hablar lo menos posible, poco y nada. En boca cerrada no entran moscas. Si somos astutos, la Corte de Apelaciones va a bajar el tipo de cambio aplicable&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/economia\/juicio-ypf-exfuncionario-macri-afirma-argentina-solo-podria-pagar-10-fallo-negociar-burford-ilegal_0_fNRH2QZYiX.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ex procurador del Tesoro de la Naci\u00f3n Bernardo Saravia Fr\u00edas -que trabaj\u00f3 durante el gobierno de Mauricio Macri- asegur\u00f3 este mi\u00e9rcoles ante los socios del Rotary Club de Buenos Aires que es &#8220;optimista&#8221; de que la Argentina pueda pagarle a los beneficiarios del fallo por la expropiaci\u00f3n de YPF mucho menos que los 16.100 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[6695,288,1245,18,100,24937,1969,3924,1109,725,3597,1563,6279,166],"class_list":["post-46579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-afirma","tag-argentina","tag-burford","tag-con","tag-del","tag-exfuncionario","tag-fallo","tag-ilegal","tag-macri","tag-negociar","tag-pagar","tag-podria","tag-seria","tag-solo"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46579"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46580"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}