{"id":46504,"date":"2025-07-30T10:03:59","date_gmt":"2025-07-30T13:03:59","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/salio-a-ver-a-sus-amigos-con-un-celular-y-500-pesos-lo-mataron-para-robarle\/"},"modified":"2025-07-30T10:03:59","modified_gmt":"2025-07-30T13:03:59","slug":"salio-a-ver-a-sus-amigos-con-un-celular-y-500-pesos-lo-mataron-para-robarle","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/salio-a-ver-a-sus-amigos-con-un-celular-y-500-pesos-lo-mataron-para-robarle\/","title":{"rendered":"Sali\u00f3 a ver a sus amigos con un celular y 500 pesos: lo mataron para robarle"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/07\/Salio-a-ver-a-sus-amigos-con-un-celular-y.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p><strong>Ignacio Villagra (22)<\/strong> no quer\u00eda trabajar m\u00e1s en la carboner\u00eda. Este martes ir\u00eda por segunda vez a una entrevista, para confirmar su nuevo empleo. Horas antes lo asesinaron de un balazo en el abdomen.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>El crimen se registr\u00f3 este lunes, a las 23.30, en el barrio Empalme, al este de la ciudad de <strong>C\u00f3rdoba<\/strong>. Seg\u00fan se cree, tres j\u00f3venes lo interceptaron para robarle en la calle Rayo Cortado al 2200, cerca del cruce con la avenida Sabatini.<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>&#8220;Nacho&#8221; hab\u00eda salido de su casa del barrio Villa Bustos para juntarse con amigos. Llevaba su tel\u00e9fono celular, la mochila y la billetera, en la que ten\u00eda apenas <strong>500 pesos<\/strong>. Su mam\u00e1, Marisa, cree que se resisti\u00f3 porque necesitaba su DNI para la entrevista laboral de la ma\u00f1ana siguiente.<\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p>Los atacantes escaparon sin concretar el robo. La v\u00edctima recibi\u00f3 un balazo letal calibre 9 mil\u00edmetros.<\/p>\n<\/div>\n<div id=\"element-body-4\">\n<p>&#8220;<strong>Cay\u00f3 la Polic\u00eda a las 5 de la ma\u00f1ana para decirme que me lo hab\u00edan matado<\/strong>&#8220;, expres\u00f3 entre l\u00e1grimas su mam\u00e1.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>En di\u00e1logo con la radio <em>Cadena 3<\/em> y el <em>El Doce TV<\/em>, cont\u00f3 que su hijo le mand\u00f3 un mensaje de WhatsApp a las diez de la noche: &#8220;<em>Mam\u00e1, qu\u00e9 hac\u00e9s, yo ya voy para all\u00e1&#8221;.<\/em><\/p>\n<\/div>\n<div id=\"element-body-7\">\n<p>A la 0.30 ella le escribi\u00f3, pero \u00e9l no respondi\u00f3 m\u00e1s. Ya lo hab\u00edan asesinado.<\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>&#8220;Se habr\u00e1 querido resistir porque ten\u00eda el documento y<strong> lo necesitaba para la entrevista de trabajo<\/strong>&#8220;, manifest\u00f3.<\/p>\n<\/div>\n<div id=\"element-body-9\">\n<p>Por el homicidio no hay detenidos, aunque un vecino del mismo barrio coment\u00f3 que una hora antes fue asaltado en la zona por tres encapuchados armados.<\/p>\n<\/div>\n<div id=\"element-body-10\">\n<p>Villagra hab\u00eda jugado al f\u00fatbol en dos equipos. Uno de ellos, Deportivo Alberdi, lo despidi\u00f3 en las redes sociales: &#8220;<em>Desde el club lamentamos esta noticia y acompa\u00f1amos a la familia de Ignacio Villagra, quien fuera v\u00edctima de la inseguridad y perdiera su vida<\/em>&#8220;.<\/p>\n<\/div>\n<div id=\"element-body-11\">\n<p>&#8220;<em>Ignacio fue jugador de nuestro y esta noticia nos cay\u00f3 muy mal, por la p\u00e9rdida y violencia e inseguridad que nos rodea. Dios consuele y fortalezca a la familia y seres queridos. Que se haga Justicia. Q.E.P.D. Ignacio<\/em>&#8220;, complet\u00f3.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/policiales\/salio-ver-amigos-celular-500-pesos-mataron-robarle_0_wH78bXC5nH.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ignacio Villagra (22) no quer\u00eda trabajar m\u00e1s en la carboner\u00eda. Este martes ir\u00eda por segunda vez a una entrevista, para confirmar su nuevo empleo. Horas antes lo asesinaron de un balazo en el abdomen. El crimen se registr\u00f3 este lunes, a las 23.30, en el barrio Empalme, al este de la ciudad de C\u00f3rdoba. Seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46505,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1084,2900,18,1589,16,1066,615,1588,40,827],"class_list":["post-46504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-amigos","tag-celular","tag-con","tag-mataron","tag-para","tag-pesos","tag-robarle","tag-salio","tag-sus","tag-ver"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46504"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46505"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}