{"id":3974,"date":"2025-02-11T17:09:28","date_gmt":"2025-02-11T20:09:28","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/el-papa-de-un-gendarme-increpo-a-bullrich-en-un-video-y-ahora-prometen-un-plan-para-darles-casas-a-los-efectivos\/"},"modified":"2025-02-11T17:09:28","modified_gmt":"2025-02-11T20:09:28","slug":"el-papa-de-un-gendarme-increpo-a-bullrich-en-un-video-y-ahora-prometen-un-plan-para-darles-casas-a-los-efectivos","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/el-papa-de-un-gendarme-increpo-a-bullrich-en-un-video-y-ahora-prometen-un-plan-para-darles-casas-a-los-efectivos\/","title":{"rendered":"El pap\u00e1 de un gendarme increp\u00f3 a Bullrich en un video y ahora prometen un plan para darles casas a los efectivos"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"cuerpo\">\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Abordada por el padre angustiado de un gendarme que reclamaba por el sueldo magro de su hijo que <strong>consum\u00eda $450 mil de los $750 mil del haber en alquiler<\/strong>, <strong>Patricia Bullrich <\/strong>le prometi\u00f3 al hombre que estaba trabajando en la entrega de viviendas para los gendarmes.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>\u201c<strong>Estamos trabajando para que nos den los planes Procrear (&#8230;) los alquileres los vamos a ir cambiando por todos los planes Procrear, que son casas<\/strong>\u201d, intent\u00f3 consolarlo la <strong>renombrada ministra de Seguridad nacional<\/strong>, aunque el Gobierno hab\u00eda disuelto en noviembre pasado el fondo fiduciario para financiar plan de <strong>construcci\u00f3n y cr\u00e9dito hipotecario creado en 2012<\/strong>.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>La imagen de Bullrich con el padre del gendarme, en la localidad salte\u00f1a de Aguas Blancas, adonde la ministra viaj\u00f3 para inaugurar la apertura de la licitaci\u00f3n <strong>para los 200 metros de alambre<\/strong> que separar\u00e1n la frontera con Bolivia desde la terminal de \u00f3mnibus, se viraliz\u00f3 instant\u00e1neamente por un video robado que registr\u00f3 la conversaci\u00f3n.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Seg\u00fan contaron a <strong>Clar\u00edn <\/strong>los colaboradores de m\u00e1xima confianza de la ministra, ella hab\u00eda sido advertida de la grabaci\u00f3n por uno de los polic\u00edas federales que la escoltaban. \u201c<strong>No le import\u00f3, porque el hombre estaba genuinamente angustiado<\/strong>\u201d, dijo.<\/p>\n<\/div>\n<div class=\"sc-198be8ec-0 cynXbu image-embed  image-embed \"><picture class=\"sc-198be8ec-1 kOjRiQ\"><source media=\"(min-width: 975px)\" width=\"720\" height=\"480\" \/><img alt=\"Luis Caputo y Patricia Bullrich. &#10;Foto: Foto Federico L\u00f3pez Claro\" loading=\"lazy\" width=\"720\" height=\"480\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/02\/El-papa-de-un-gendarme-increpo-a-Bullrich-en-un.jpg\"\/><span class=\"epigraphe\">Luis Caputo y Patricia Bullrich.<br \/>\nFoto: Foto Federico L\u00f3pez Claro<\/span><span class=\"bkg\"\/><span class=\"picture-open\"><button class=\"open-image\" aria-label=\"Open Image\"\/><\/span><\/picture><\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Las declaraciones de Bullrich volvieron a dominar parte de la agenda horas despu\u00e9s, cuando el Gobierno anunci\u00f3 que hab\u00eda eliminado la Secretar\u00eda de Desarrollo Territorial, H\u00e1bitat y Vivienda a trav\u00e9s del <strong>decreto 70\/25<\/strong>. El Gobierno ya hab\u00eda eliminado los fondos fiduciarios que habilitaban las l\u00edneas de cr\u00e9dito del programa de vivienda social y el mencionado Procrear.<\/p>\n<\/div>\n<p><h2>48 mil viviendas en ejecuci\u00f3n pero sin terminar<\/h2>\n<\/p>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Cuando Javier Milei asumi\u00f3 la presidencia, <strong>hab\u00eda 48 mil viviendas en todo el pa\u00eds en proceso de ejecuci\u00f3n<\/strong> que deb\u00edan terminarse en 2024. Otro tanto deb\u00edan completarse este a\u00f1o. En total se trataba de una <strong>inversi\u00f3n equivalente a los $ 6 billones<\/strong>.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Adem\u00e1s del Procrear I y Procrear II, se contaban 18 mil casas del FONAVI, y viviendas de los programas Reconstruir, Casita Propia, Habitar Comunidad y Casa Activa, entre otros, y 10 mil lotes con servicio. <\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p><strong>Seg\u00fan pudo saber este diario en base al testimonio de altas fuentes del Ejecutivo, Bullrich pretende avanzar con la entrega de parte de ese universo de viviendas a agentes de Fuerzas de Seguridad, en particular a los de Gendarmer\u00eda y Prefectura, que son reasignados -en promedio- cada dos a\u00f1os a zonas de frontera. Las Fuerzas Armadas, en cambio, tienen -adem\u00e1s de vastas propiedades y campos que arrendan- una cultura de cuarteles que garantiza vivienda para los soldados.<\/strong><\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>En Seguridad tomaron nota de que el volumen de traslados de uniformados a ciudades como Or\u00e1n, por ejemplo, <strong>rompe el mercado de alquileres<\/strong> que <strong>suben exponencialmente<\/strong>. \u201c<strong>Especulan y se aprovechan<\/strong>\u201d, se quejan en el gabinete a pesar de que el Presidente suele repetir que el mercado nunca se equivoca.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Existen casos m\u00e1s particulares, como el de gendarmes y prefectos que deben vivir en inmediaciones cercanas u hoteles en zonas de turismo de lujo, como en el Chalt\u00e9n.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>En Seguridad descuentan que el ministro de Econom\u00eda <strong>Luis Caputo<\/strong>, que tiene bajo su cargo a la secretar\u00eda de Obras P\u00fablicas, <strong>ya est\u00e1 al tanto del pedido de Bullrich<\/strong>.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>La ministra <strong>logr\u00f3 arrancarle un aumento para las 4 fuerzas federales<\/strong> y el servicio penitenciario muy por encima de la pauta salarial que el Gobierno baja para el resto de los estatales y privados. \u201cEl 5 por ciento m\u00e1s el 1,5, m\u00e1s el uno, estamos en 7.89%. Nadie est\u00e1 (en esos valores). <strong>Los camioneros cerraron en el 1%. <\/strong>T\u00e9ngame confianza, yo estoy con ustedes\u201d, intent\u00f3 persuadir Bullrich a su interlocutor.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>En Econom\u00eda, por ahora, <strong>nadie dio se\u00f1ales del supuesto plan de la ministra<\/strong> que requerir\u00e1 de erogaciones para terminar obras. A trav\u00e9s de un comunicado oficial, desde la Cartera que conduce Caputo aclararon que su intenci\u00f3n es <strong>darles los proyectos a las provincias y\/o municipios seg\u00fan requieran<\/strong>. Adem\u00e1s, entregar\u00e1n una porci\u00f3n de ellas a la Agencia de Administraci\u00f3n de Bienes del Estado que podr\u00eda reasignarlas o bien venderlas en medio del plan de liquidaci\u00f3n de activos que el organismo puso en marcha en 2024.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>\u201cCreemos en una pol\u00edtica de vivienda <strong>gestionada por las provincias y los municipios<\/strong>, impulsada principalmente por las inversiones del sector privado\u201d, expresaron. Adem\u00e1s pasar\u00e1 a depender de Obras P\u00fablicas la subsecretar\u00eda de Integraci\u00f3n Socio-Urbana, que casi no tiene presupuesto para avanzar en la urbanizaci\u00f3n de barrios populares, pero la controla <strong>Sebasti\u00e1n Pareja<\/strong>, alfil de <strong>Karina Milei y presidente del partido<\/strong> bonaerense de La Libertad Avanza<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Bullrich piensa, en particular, en viviendas ubicadas en distintos puntos del <strong>conurbano bonaerense<\/strong>, como en Avellaneda. No descarta que los uniformados que resultaran beneficiados con esas viviendas -a trav\u00e9s de un cr\u00e9dito blando- pudieran alquilarlas en el caso de que no la ocuparan por motivos laborales.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>El intendente de esa localidad, el ex ministro de Vivienda <strong>Jorge Ferraresi<\/strong>, hizo una presentaci\u00f3n en enero para reclamar por las 158 viviendas que fueron discontinuidad en los predios <strong>Entre R\u00edos (Pi\u00f1eiro) y Belgrano 678<\/strong> (Avellaneda Centro) que hab\u00eda cedido para el programa. \u201cExigiremos, por medio de las <strong>acciones legales que correspondan, la restituci\u00f3n de los inmuebles aportados que fueron abandonados por el Estado Nacional<\/strong> para poder darles continuidad con fondos propios\u201d, reclam\u00f3 en su momento.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p><strong>Como cont\u00f3 Clar\u00edn<\/strong>, la recomposici\u00f3n salarial que el Gobierno apur\u00f3 cuando trascendi\u00f3 el malestar de las Fuerzas de Seguridad y replic\u00f3 r\u00e1pidamente tambi\u00e9n para las Fuerzas Armadas, no conform\u00f3 a los uniformados. \u201cEspero que sea pronto, doctora, porque no va m\u00e1s\u201d, le dijo el padre del gendarme.<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/politica\/papa-gendarme-increpo-bullrich-video-ahora-prometen-plan-darles-casas-efectivos_0_IHl3m2jNMh.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abordada por el padre angustiado de un gendarme que reclamaba por el sueldo magro de su hijo que consum\u00eda $450 mil de los $750 mil del haber en alquiler, Patricia Bullrich le prometi\u00f3 al hombre que estaba trabajando en la entrega de viviendas para los gendarmes. \u201cEstamos trabajando para que nos den los planes Procrear [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1412,584,565,6014,4675,4872,6012,28,2919,16,33,6013,200],"class_list":["post-3974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-ahora","tag-bullrich","tag-casas","tag-darles","tag-efectivos","tag-gendarme","tag-increpo","tag-los","tag-papa","tag-para","tag-plan","tag-prometen","tag-video"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3974"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/3975"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}