{"id":3970,"date":"2025-02-11T17:00:38","date_gmt":"2025-02-11T20:00:38","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/tras-la-baja-de-las-retenciones-al-campo-se-registraron-ventas-al-exterior-de-los-principales-granos-por-mas-us-900-millones\/"},"modified":"2025-02-11T17:00:38","modified_gmt":"2025-02-11T20:00:38","slug":"tras-la-baja-de-las-retenciones-al-campo-se-registraron-ventas-al-exterior-de-los-principales-granos-por-mas-us-900-millones","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/tras-la-baja-de-las-retenciones-al-campo-se-registraron-ventas-al-exterior-de-los-principales-granos-por-mas-us-900-millones\/","title":{"rendered":"Tras la baja de las retenciones al campo, se registraron ventas al exterior de los principales granos por m\u00e1s US$ 900 millones"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/02\/Tras-la-baja-de-las-retenciones-al-campo-se-registraron.jpg\" \/><\/p>\n<div id=\"cuerpo\">\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Tras la baja temporal de las retenciones a los principales granos, se registraron exportaciones por m\u00e1s de US$ 900 millones y los productores vendieron m\u00e1s de 5 millones de toneladas.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Desde el 27 de enero al lunes 10 de febrero, el acumulado de ventas de soja del productor era de 2 millones de toneladas. Y en el caso del ma\u00edz, los productores comercializaron 1,9 millones de toneladas en ese mismo per\u00edodo. En trigo, el acumulado superaba los 850 mil toneladas y en cebada, 305 mil toneladas. Luego, girasol alcanzaba las 211 mil toneladas, y el sorgo, 48 mil toneladas.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Este impulso a que el productor venda su producci\u00f3n tuvo que ver con una mejora en el valor. &#8220;Hoy tenemos una soja disponible que est\u00e1 arriba de 320.000 pesos, un ma\u00edz que est\u00e1 en el orden de los 215.000-220 000 pesos en el mercado disponible. El trigo tambi\u00e9n, 220 000 pesos. Es decir, se empez\u00f3 a mostrar alguna recuperaci\u00f3n&#8221;, dijo<strong> Marcos Hermansson<\/strong>, corredor, presidente del Centro de Corredores y Agentes de la Bolsa de Cereales y directivo de Matba-Rofex. Previo a la baja de las retenciones, la soja cotizaba a $290.000, el ma\u00edz, a $ 205.000 y el trigo, a $195.000.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>A lo que sum\u00f3 que la semana pasada la cotizaci\u00f3n de la Soja-Mayo 2025 estuvo en US$ 300 en un contexto donde &#8220;va a sobrar&#8221; producci\u00f3n porque &#8220;hay una mayor oferta que demanda&#8221;. &#8220;<strong>Es un valor para que el productor no le pierda pisada<\/strong>&#8220;, remarc\u00f3. Y acot\u00f3 un dato importante: &#8220;Se oper\u00f3 Soja-Mayo 2026 en Matba-Rofex a US$ 292&#8221;.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>En cuanto a las Declaraciones Juradas de Ventas al Exterior (DJVE), el complejo sojero pic\u00f3 en punta. Desde que se puso en marcha la baja temporal de las al\u00edcuotas hasta el lunes se hab\u00edan registrado 326 mil toneladas de aceite de soja, 198 mil toneladas de poroto y 485 mil toneladas de subproductos (harina).<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Luego, se declararon 653 mil toneladas de ma\u00edz, 490 mil toneladas de trigo pan, 20 mil toneladas de harina de trigo; mientras que en el complejo girasolero, se registraron 19.316 toneladas de aceite, 284 toneladas de semillas y 8.350 toneladas de subproductos.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>En cuanto a la cebada, se declararon 133.765 toneladas de la forrajera y 64.097 toneladas de la cervecera.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Seg\u00fan los c\u00e1lculos del exsubsecretario de Mercados Agroepcuarios y titular de RIA Consultores, Javier Preciado Pati\u00f1o,<strong> esto representa ingresos por US$ 910 millones.<\/strong><\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Cabe resaltar que en enero las empresas del sector agroindustrial liquidaron la suma de U$S 2.073 millones, un 36% mayor en relaci\u00f3n al mismo mes del a\u00f1o 2024, as\u00ed como una suba del 5% en relaci\u00f3n al mes de diciembre de 2024.<\/p>\n<\/div>\n<p><h2>Baja de retenciones<\/h2>\n<\/p>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Las nuevas al\u00edcuotas de pago de retenciones ser\u00e1n temporales (hasta el 30 de junio) en los principales cultivos como la soja (poroto), que pasar\u00e1 del 33 al 26% y sus derivados (aceite y harina) que bajar\u00e1n del 31 al 24,5%.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Tambi\u00e9n se reducir\u00e1n los derechos para la exportaci\u00f3n para el trigo (12 a 9,5%), la cebada (12 a 9,5%), el ma\u00edz (12 a 9,5%), el girasol (7 a 5,5%) y el sorgo (12 a 9,5%).<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>Fue bajo el Decreto 38\/2025, que pone una condici\u00f3n sustancial para que el campo pueda acceder al alivio: hay que liquidar el 95% de lo que se declar\u00f3 en 15 d\u00edas h\u00e1biles.<\/p>\n<\/div>\n<div class=\"sc-80531b6b-0 chRIGJ container-text text-embed\">\n<p>En este contexto, la mesa de enlace se reuni\u00f3 con el ministro de Econom\u00eda, Luis Caputo, y le solicit\u00f3 la continuidad de la baja de las retenciones hasta despu\u00e9s del 30 de junio. Pero la respuesta del funcionaria fue negativa. Incluso, un d\u00eda antes de ese encuentro, hab\u00eda dicho que era &#8220;hasta donde le daba la plata&#8221;. &#8220;El equilibrio fiscal no lo vamos a arriesgar de ninguna forma&#8221;, aseguro.<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/rural\/baja-retenciones-campo-registraron-ventas-exterior-principales-granos-us-900-millones_0_i4C3YMOxKM.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la baja temporal de las retenciones a los principales granos, se registraron exportaciones por m\u00e1s de US$ 900 millones y los productores vendieron m\u00e1s de 5 millones de toneladas. Desde el 27 de enero al lunes 10 de febrero, el acumulado de ventas de soja del productor era de 2 millones de toneladas. Y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[524,958,1520,6009,48,28,155,1065,142,2428,6007,525,312,6008],"class_list":["post-3970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-baja","tag-campo","tag-exterior","tag-granos","tag-las","tag-los","tag-mas","tag-millones","tag-por","tag-principales","tag-registraron","tag-retenciones","tag-tras","tag-ventas"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3970"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/3971"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}