{"id":29048,"date":"2025-05-27T19:34:37","date_gmt":"2025-05-27T22:34:37","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/un-italiano-paso-17-dias-secuestrado-en-nueva-york-por-dos-hombres-que-buscaban-robarle-sus-criptomonedas\/"},"modified":"2025-05-27T19:34:37","modified_gmt":"2025-05-27T22:34:37","slug":"un-italiano-paso-17-dias-secuestrado-en-nueva-york-por-dos-hombres-que-buscaban-robarle-sus-criptomonedas","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/un-italiano-paso-17-dias-secuestrado-en-nueva-york-por-dos-hombres-que-buscaban-robarle-sus-criptomonedas\/","title":{"rendered":"un italiano pas\u00f3 17 d\u00edas secuestrado en Nueva York por dos hombres que buscaban robarle sus criptomonedas"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/05\/un-italiano-paso-17-dias-secuestrado-en-Nueva-York-por.jpg\" \/><\/p>\n<div id=\"element-body-0\">\n<p>Se profundiza la investigaci\u00f3n por el caso de <strong>un empresario italiano<\/strong> dedicado a las criptomonedas que estuvo <strong>secuestrado durante 17 d\u00edas <\/strong>por dos hombres que buscaban robarle su fortuna. Las autoridades detuvieron primero a al inversor cripto John Woeltz, y ahora se sum\u00f3 a la lista de sospechosos William Duplessie, tambi\u00e9n dedicado a los tokens digitales.<\/p>\n<\/div>\n<div id=\"element-body-1\">\n<p>Duplessie (32 a\u00f1os) se entreg\u00f3 a la polic\u00eda este martes. Seg\u00fan la polic\u00eda, enfrenta cargos de <strong>secuestro, agresi\u00f3n, privaci\u00f3n ileg\u00edtima de libertad y posesi\u00f3n criminal de un arma<\/strong>. El viernes, Woeltz (37 a\u00f1os) hab\u00eda sido arrestado y acusado de participar en el secuestro, poco despu\u00e9s de que <strong>la v\u00edctima lograra escaparse<\/strong> de una lujosa mansi\u00f3n en Manhattan (Nueva York).<\/p>\n<\/div>\n<div id=\"element-body-2\">\n<p>Tanto Duplessie como Woeltz parecen ser empresarios centrados en criptomonedas. En sus perfiles en Internet, Duplessie aparece como cofundador y jefe de abastecimiento de Pangea Blockchain Fund e inversor en otras empresas basadas en la blockchain.<\/p>\n<\/div>\n<div id=\"element-body-3\">\n<p>Las autoridades dijeron que Duplessie y Woeltz convencieron a la v\u00edctima -un empresario italiano de 28 a\u00f1os- para ir a <strong>una lujosa casa de ocho dormitorios en el exclusivo barrio SoHo<\/strong>, en Manhattan, el 6 de mayo pasado. Ten\u00edan como objetivo robarle su fortuna en <strong>bitcoin<\/strong>. El hombre dijo que hab\u00eda sido <strong>golpeado duramente, drogado, electrocutado y amenazado de muerte <\/strong>durante 17 d\u00edas.<\/p>\n<\/div>\n<div id=\"element-body-5\">\n<p>En su declaraci\u00f3n a la polic\u00eda, la v\u00edctima dijo que<strong> le ataron las mu\u00f1ecas<\/strong>, le dieron <strong>descargas el\u00e9ctricas<\/strong>, lo <strong>golpearon con una pistola<\/strong>, le cortaron la pierna con un serrucho y le obligaron a fumar de <strong>una pipa de crack.<\/strong> En un momento dado, dijo, lo colgaron desde el extremo superior de las escaleras de la casa.<\/p>\n<\/div>\n<div id=\"element-body-6\">\n<p>Creyendo que pronto lo matar\u00edan, la v\u00edctima dijo que accedi\u00f3 el viernes por la ma\u00f1ana a darle a los hombres<strong> acceso a la contrase\u00f1a. <\/strong>Pero cuando los hombres fueron a recuperar su computadora, la v\u00edctima pudo escapar de la casa y hacer se\u00f1as a un agente de tr\u00e1fico en la calle. Finalmente, <strong>logr\u00f3 escapar, ensangrentado y descalzo<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-7\">\n<p>El hombre fue hospitalizado con <strong>heridas en las mu\u00f1ecas<\/strong> consistentes con haber estado atado, <strong>cortes en la cara y otras lesiones<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-8\">\n<p>Seg\u00fan la fiscal\u00eda, en el registro de la casa aparecieron numerosas pruebas, entre ellas <strong>coca\u00edna<\/strong>, un <strong>serrucho<\/strong>, <strong>alambre<\/strong>, <strong>chalecos antibalas<\/strong>, lentes de visi\u00f3n nocturna, <strong>munici\u00f3n <\/strong>y fotos polaroid de la v\u00edctima con una pistola apunt\u00e1ndole a la cabeza y una pipa de crack en la boca.<\/p>\n<\/div>\n<div id=\"element-body-11\">\n<p>El episodio se produce en medio de un <strong>repunte de los robos de criptomonedas<\/strong>, incluida una reciente ola de violencia dirigida a los adinerados poseedores de criptomonedas.<\/p>\n<\/div>\n<div id=\"element-body-12\">\n<p>A principios de mes, en <strong>Par\u00eds<\/strong>, el<strong> padre de un criptoempresario <\/strong>fue rescatado por la polic\u00eda despu\u00e9s de que <strong>los asaltantes le cortaran un dedo<\/strong>. En otro caso, unos delincuentes <strong>intentaron secuestrar a la hija de un criptoempresario<\/strong> en plena calle, pero no lo consiguieron.<\/p>\n<\/div>\n<div id=\"element-body-13\">\n<p>En Agosto de 2024, en Danbury, <strong>Connecticut<\/strong>, una pareja fue obligada a salir de su auto, golpeada y metida en una furgoneta en un plan de rescate dirigido a su hijo, que seg\u00fan las autoridades estaba implicado en un robo de criptomonedas por US$240 millones la semana anterior.<\/p>\n<\/div>\n<div id=\"element-body-14\">\n<p>Un informe reciente del FBI estima en <strong>US$ 16.600 millones <\/strong>las p\u00e9rdidas relacionadas con la delincuencia en Internet en 2024, casi un tercio en comparaci\u00f3n con el a\u00f1o anterior. <strong>Las v\u00edctimas de robos de criptomonedas declararon las mayores p\u00e9rdidas,<\/strong> una cantidad que ascendi\u00f3 a m\u00e1s de US$6500 millones.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/mundo\/torturado-bitcoins-italiano-paso-17-dias-secuestrado-nueva-york-hombres-buscaban-robarle-criptomonedas_0_yssMenn7mL.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se profundiza la investigaci\u00f3n por el caso de un empresario italiano dedicado a las criptomonedas que estuvo secuestrado durante 17 d\u00edas por dos hombres que buscaban robarle su fortuna. Las autoridades detuvieron primero a al inversor cripto John Woeltz, y ahora se sum\u00f3 a la lista de sospechosos William Duplessie, tambi\u00e9n dedicado a los tokens [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3349,7644,500,59,2009,8298,19,158,142,615,8709,40,1088],"class_list":["post-29048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-buscaban","tag-criptomonedas","tag-dias","tag-dos","tag-hombres","tag-italiano","tag-nueva","tag-paso","tag-por","tag-robarle","tag-secuestrado","tag-sus","tag-york"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/29048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=29048"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/29048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/29049"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=29048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=29048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=29048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}