{"id":11985,"date":"2025-03-15T06:44:28","date_gmt":"2025-03-15T09:44:28","guid":{"rendered":"https:\/\/13.com.ar\/index.php\/cafe-hansen-y-la-cultura-del-tango\/"},"modified":"2025-03-15T06:44:28","modified_gmt":"2025-03-15T09:44:28","slug":"cafe-hansen-y-la-cultura-del-tango","status":"publish","type":"post","link":"https:\/\/13.com.ar\/index.php\/cafe-hansen-y-la-cultura-del-tango\/","title":{"rendered":"Caf\u00e9 Hansen y la cultura del tango"},"content":{"rendered":"<p> <br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/13.com.ar\/wp-content\/uploads\/2025\/03\/Cafe-Hansen-y-la-cultura-del-tango.jpg\" \/><\/p>\n<div>\n<p>Donde ahora est\u00e1 el Planetario, all\u00ed funcion\u00f3<em> Lo de Hansen<\/em>. Lo sabemos porque hace unos a\u00f1os se encontraron rastros. Fundado en 1877 por Juan Hansen, inmigrante alem\u00e1n, pas\u00f3 a manos de Anselmo Tarana tras la muerte de su due\u00f1o original, en 1892. Fue la <strong>cuna del tango a comienzos del siglo XX<\/strong>. Hasta 1912, cuando fue demolido. Una letra y una pel\u00edcula lo har\u00edan resurgir. Cuando en 1937 se estren\u00f3 <em>Los muchachos de antes no usaban gomina<\/em>, el p\u00fablico se transport\u00f3 hasta las maderas del Hansen. Ya antes, la letra de <em>Tiempos viejos<\/em> (1926) \u2013escrita por Manuel Romero con m\u00fasica de Francisco Canaro\u2013, tambi\u00e9n nos lleva hasta su piso de baile:<em> \u201c\u00bfTe acord\u00e1s, hermano, la Rubia Mireya \/ que quit\u00e9 en lo de Hansen al guapo Rivera?\u201d <\/em>.<\/p>\n<\/div>\n<div>\n<p>Cuenta la leyenda que por el 1900, cuando sonaba <em>El Esquinazo, <\/em>el p\u00fablico se pon\u00eda a seguir el ritmo<strong> golpeando contra las mesas y los cristales.<\/strong> Tal es as\u00ed que tuvieron que prohibir la canci\u00f3n, por temor a que se viniera abajo el local. Por entonces <em>El Esquinazo<\/em> no ten\u00eda letra, que se agregar\u00eda despu\u00e9s. Todo esto es de antes de <em>La Cumparsita<\/em> \u2013que reci\u00e9n aparecer\u00eda en 1917\u2013. El siglo XX naci\u00f3 nost\u00e1lgico. Pero \u00bfcu\u00e1ndo se invent\u00f3 la nostalgia? Podr\u00eda decirse que con <em>Tiempos viejos<\/em>, en el 26.<\/p>\n<\/div>\n<div>\n<p>\u00bfY a cuento de qu\u00e9 toda esta investigaci\u00f3n? Quiz\u00e1 un poco en homenaje a nuestros padres \u2013el m\u00edo se llama Eulogio\u2013, que hicieron del tango nuestra canci\u00f3n de cuna. O al poeta Jorge Quiroga, con quien los domingos a la ma\u00f1ana nos reun\u00edamos a escuchar 2&#215;4 en Barracas. Podemos tocar temas actuales. Para que nuestros mayores reciban un poco de novedad. Pero: \u00bfpor qu\u00e9 no dejarnos llevar por sus temas: <em>Milonga del 900<\/em> y <em>Buenos Aires Querid<\/em>o.<\/p>\n<\/div>\n<div>\n<p>La representaci\u00f3n del caf\u00e9 en las letras de tango es un tema can\u00f3nico. <em>Sentimiento gaucho <\/em>(1924) de Francisco y Rafael Canaro nos lleva hasta el <em>Viejo Almac\u00e9n<\/em> de Paseo Col\u00f3n. Pero en el cielo de los tangos que hablan de bares el que m\u00e1s brilla es <em>Cafet\u00edn de Buenos Aires<\/em>. Con letra de Disc\u00e9polo, fue compuesto para la pel\u00edcula <em>Corrientes, calle de ensue\u00f1os<\/em>. Si comparamos los dos tangos notamos que los hombres que han perdido la fe en el <em>Viejo Almac\u00e9n<\/em>, se transforman en los \u201csabiondos y suicidas\u201d del Cafet\u00edn. El cantor que en 1948 recuerda sus <strong>tiempos de \u00f1ata contra el vidrio<\/strong>, est\u00e1 evocando el interior de los bares de los a\u00f1os 20. En el cambio de \u00e9poca, va de 1920 a 1940, el tipo humano que visita los bares cambia, se hace m\u00e1s cosmopolita. Esa \u201cmezcla milagrosa\u201d es la modernidad.<\/p>\n<\/div>\n<div>\n<p>El hombre que encontramos en el <em>Viejo Almac\u00e9n<\/em> le muestra al cantor una<strong> filosof\u00eda estoica de la derrota: <\/strong>\u201cSabe que es condici\u00f3n \/ De var\u00f3n el sufrir\u201d. La filosof\u00eda cruel de no pensar m\u00e1s en uno reaparece en Cafet\u00edn. Y en <em>Uno<\/em>: \u201cSi yo tuviera el coraz\u00f3n \/ El mismo que perd\u00ed\u201d. \u00bfPor qu\u00e9 no pensar que el coraz\u00f3n perdido del cantor de <em>Uno<\/em> no es, acaso, el mismo que, unas d\u00e9cadas antes, hab\u00eda latido en el pecho de un borracho perdido de Paseo Col\u00f3n?<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.clarin.com\/opinion\/cafe-hansen-cultura-tango_0_afexzPHokm.html\">Fuente Clarin.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Donde ahora est\u00e1 el Planetario, all\u00ed funcion\u00f3 Lo de Hansen. Lo sabemos porque hace unos a\u00f1os se encontraron rastros. Fundado en 1877 por Juan Hansen, inmigrante alem\u00e1n, pas\u00f3 a manos de Anselmo Tarana tras la muerte de su due\u00f1o original, en 1892. Fue la cuna del tango a comienzos del siglo XX. Hasta 1912, cuando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[6291,4149,100,11845,9979],"class_list":["post-11985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-cafe","tag-cultura","tag-del","tag-hansen","tag-tango"],"_links":{"self":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11985"}],"version-history":[{"count":0,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11986"}],"wp:attachment":[{"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/13.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}